{"text_format":"1","workbook":"xlsx","n_sheets":14,"sheets":["Form Instructions","Project Information","Checklist & Acknowledgement","Terms and Conditions","Technical Requirements","Equipment Incentives","Equipment Input Instructions","Equipment Input","Input Key","Measure Summary","Validation","Lookups","Version Tracking","AEG Import"],"not_rendered":{"charts":0,"images":7,"macros":1,"external_links":0,"defined_names":1543,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Form Instructions","index":0,"n_rows":12,"n_cols":4,"rows_kept":12,"cut":false,"hidden":false,"merged":[[0,1,1,3],[2,1,2,3],[8,1,8,3],[11,1,12,1],[11,3,13,3]]}
[]
[]
[null,"                   Food Service and High-Efficiency Equipment Application\nDominion Energy South Carolina, Inc."]
[]
[]
[]
[]
[]
[null,"*If an error occurs when using buttons above, manually navigate to appropriate tab."]
[]
[null,null,null,{"$f":"\"Version \" & 'Version Tracking'!C4","v":"Version 14.3"}]
[null,"Application and Instructions\nThe EnergyWise for Your Business Program is designed to help non-residential\ncustomers replace aging, inefficient equipment and systems with energy-efficient technologies. The program provides customers with incentives and technical assistance that will facilitate the installation of premium efficient equipment. For each program year (December 1–November 30), EnergyWise for Your Business incentive payments are capped per Customer Federal tax ID number at $100,000 per Project type. Details of the program, including incentive levels and technical requirements, are subject to change without prior notice. \n\nEligible Participants\nEnergyWise for Your Business is open to all non-residential electric customers within our service territory, except for customers eligible for Rate 23 and certain large retail customers that have elected to opt out of the Demand Side Management (DSM) programs by notifying us in writing using the Opt-Out form.\n\nEligible Equipment\nEligible equipment and incentive amounts are listed on the Equipment Tabs.  Eligible equipment include High Efficiency Food Preparation Equipment, Ice Machines,  Refrigerators and Freezers, Clothes Washers, High Efficiency Refrigerator Components, and Plug Load Controls.  These measures are subject to the associated technical eligibility criteria described on the Technical Requirements tab. All equipment must be new; used or refurbished equipment is not eligible.  This form is applicable to installation of high-efficiency equipment and controls in retrofits and new construction.\n\nPre-Approval Requirements\nAll projects require pre-approval prior to ordering, purchasing or installing any equipment except for eligible Food Service and High-Efficiency projects with total incentives less than or equal to $1,000.  After the application has been pre-approved by us, the customer will be notified in writing, assigned a project identification number, and given any specific instructions. The customer may then purchase and install the pre-approved equipment. For projects not requiring pre-approval, the applicant can purchase and install the qualifying equipment and submit a completed application form, supporting documentation and invoice within 60 days of the project invoice date.\n\nQuestions\nIf you have questions about the program, call 877-784-7234, email EnergyExperts@SC.DominionEnergyAccount.com or visit www.DominionEnergySC.com/ForYourBusiness.",null,"Participation Instructions\nPlease review the program Terms and Conditions tab and the Technical Requirements tab for all program rules and requirements.  Tabs colored Blue should be filled in by applicant.  Applicant should complete at least one applicable Blue Equipment tab for submission. \n\nStep 1\nReview program materials to confirm your proposed equipment meets program requirements. Visit the program website at www.DominionEnergySC.com/ForYourBusiness or contact us at EnergyExperts@SC.DominionEnergyAccount.com or 877-784-7234 with any questions about eligibility.\n\nStep 2\n→  Complete the Project Information tab.  Please indicate the mailing address for all correspondence under the Customer Contact Information including incentive checks if applicable.  Please indicate if the incentive payment should be made payable to the customer of record or a third party, such as the installation contractor. All incentive payments require authorization from the customer of record. IRS Form W-9 must be completed for the party receiving the incentive payment from us. Physical signature is required on W-9. This form is available at www.irs.gov. Regardless of who is receiving the incentive payment, the customer’s Federal tax ID number must be provided on this tab.\n \n→  Complete Equipment Input Tab.\n\n→ Complete the Checklist and Acknowledgement tab.  Provide customer signature and verify that all required information and documentation are included for submission to us.  Incomplete applications will not be accepted and will be returned to the customer for completion.\n\n→ Complete application packages must be submitted by email.\nEmail: EnergyExperts@SC.DominionEnergyAccount.com. \n\nStep 3\nApplications will be processed and we will notify the customer in writing when the review is complete and funds have been reserved. Upon receipt of program pre-approval, customers may purchase and install their energy efficient equipment. We will notify customers if an inspection of the facility is necessary prior to pre-approval.  Applications will be processed and we will notify the customer in writing when the review is complete and funds have been reserved. Upon receipt of program pre-approval, customers may purchase and install their energy efficient equipment. We will notify customers if an inspection of the facility is necessary prior to pre-approval.  Eligible Food Service Equipment and High-Efficiency projects with total incentives less than or equal to $1,000 do not require pre-approval from us. The applicant may purchase and install the qualifying equipment and submit a completed application form and supporting documentation, including final invoice, within 60 days of the project's invoice date. Any changes in the proposed equipment, quantities, or operating conditions must be approved by us prior to implementing.\n\nStep 4\nFor all projects requiring pre-approval, upon project completion, please return the signed customer acknowledgment at bottom of the pre-approval letter along with proof of purchase. Proof of purchase must include an itemized invoice for all Energy Conservation Measures (ECMs) that may qualify for the EnergyWise for Your Business incentive. Each individual product or model number must include the corresponding costs and quantity. We will notify customers if an inspection of the facility is necessary prior to final payment processing."]

{"sheet":"Project Information","index":1,"n_rows":43,"n_cols":15,"rows_kept":43,"cut":false,"hidden":false,"merged":[[41,1,41,14],[42,0,42,9],[38,0,38,9],[39,0,39,2],[39,3,39,9],[39,11,39,14],[40,0,40,5],[40,6,40,9],[40,10,40,12],[40,13,40,14],[37,0,37,3],[31,0,31,2],[31,3,31,9],[31,11,31,14],[32,0,32,2],[32,3,32,6],[32,8,32,9],[32,11,32,14],[33,0,33,14],[34,0,34,14],[35,0,35,14],[36,0,36,2],[36,3,36,9],[29,0,29,2],[29,3,29,14],[30,0,30,2],[30,3,30,6],[30,8,30,9],[30,11,30,14],[24,0,24,14],[24,16,28,31],[25,0,25,14],[26,0,26,15],[27,0,27,14],[28,0,28,2],[28,3,28,14],[22,0,22,2],[22,3,22,9],[22,11,22,14],[23,0,23,2],[23,3,23,6],[23,8,23,9],[23,11,23,14],[19,0,19,2],[19,3,19,14],[20,0,20,2],[20,3,20,14],[21,0,21,2],[21,3,21,6],[21,8,21,9],[21,11,21,14],[18,0,18,14],[13,0,13,14],[14,0,14,2],[14,3,14,6],[14,8,14,9],[14,11,14,14],[15,0,15,2],[15,3,15,9],[15,11,15,14],[16,0,16,2],[16,3,16,6],[16,8,16,9],[16,11,16,14],[17,0,17,14],[8,11,8,13],[9,0,9,5],[10,9,10,11],[11,0,11,14],[12,0,12,2],[12,3,12,14],[7,0,7,9],[3,0,3,2],[3,3,3,9],[3,10,3,12],[3,13,3,14],[4,0,4,2],[4,3,4,9],[4,10,4,12],[4,13,4,14],[5,0,5,2],[5,3,5,6],[5,8,5,9],[5,11,5,14],[6,0,6,12],[0,0,0,14],[1,0,1,14],[2,0,2,2],[2,3,2,9],[2,10,2,12],[2,13,2,14]]}
["Fill in Blue and Orange Cells Only!"]
["PROJECT INFORMATION"]
["Application Date    ",null,null,null,null,null,null,null,null,null,"Expected Completion Date"]
["Company Name    ",null,null,null,null,null,null,null,null,null,"Electric Account # "]
["Street Address (of the facility) ",null,null,null,null,null,null,null,null,null,"Customer Federal Tax ID "]
["City   ",null,null,null,null,null,null,"State   ","SC",null,"Zip  "]
["Building Type (select one)"]
[]
[null,null,null,null,null,null,null,null,null,null,null,"Please indicate \"other\" type:"]
["Project Type (select one)"]
[]
["CUSTOMER CONTACT INFORMATION"]
["Mailing Address"]
["(where all correspondence will be mailed, including incentive check if payment is to the customer)"]
["City   ",null,null,null,null,null,null,"State   ",null,null,"Zip  "]
["Contact Person     ",null,null,null,null,null,null,null,null,null,"Title"]
["Telephone No.       ",null,null,null,null,null,null,"Fax No.",null,null,"Email "]
[]
["CONTRACTOR INFORMATION"]
["Company Name  "]
["Street Address   "]
["City   ",null,null,null,null,null,null,"State   ",null,null,"Zip  "]
["Contact Person     ",null,null,null,null,null,null,null,null,null,"Title"]
["Telephone No.       ",null,null,null,null,null,null,"Fax No.",null,null,"Email "]
[]
["Please indicate if the Customer or Contractor should be primary point of contact for this project.  If another party should be primary point of contact, please indicate below:"]
["             Customer                                          Contractor                                   Other (fill out below)"]
["PRIMARY POINT OF CONTACT (IF APPLICABLE)"]
["Company Name  "]
["Street Address   "]
["City   ",null,null,null,null,null,null,"State   ",null,null,"Zip  "]
["Contact Person     ",null,null,null,null,null,null,null,null,null,"Title"]
["Telephone No.       ",null,null,null,null,null,null,"Fax No.",null,null,"Email "]
[]
["PAYMENT INFORMATION"]
["Payment to: "]
["Federal Tax ID # (of recipient)"]
["Tax Status of Recipient (select one)"]
[]
["Customer Name",null,null,null,null,null,null,null,null,null,"Title"]
["Customer Signature (if payment to contractor, Customer must type his/her name in the orange box to the right and check the box below)    ",null,null,null,null,null,null,null,null,null,"Date (XX/XX/XXXX)"]
[null,"I understand and intend that my electronic, PDF or facsimile signature be accepted and have the same force and effect as an original signature."]
["Dominion Energy South Carolina, Inc. Food Service and High-Efficiency Equipment Application - Electronic Version",null,null,null,null,null,null,null,null,null,null,null,null,"Version",{"$f":"'Version Tracking'!C4","v":14.3}]

{"sheet":"Checklist & Acknowledgement","index":2,"n_rows":22,"n_cols":13,"rows_kept":22,"cut":false,"hidden":false,"merged":[[20,1,20,14],[14,1,14,14],[15,0,15,14],[16,0,16,14],[18,0,19,2],[18,3,19,7],[18,8,18,9],[18,10,18,14],[19,8,19,12],[19,13,19,14],[12,0,13,2],[12,3,13,7],[12,8,12,9],[12,10,12,14],[13,8,13,12],[13,13,13,14],[11,0,11,14],[0,0,0,14],[1,0,1,14],[2,0,2,14],[3,0,3,14],[4,0,4,14],[5,0,5,14],[6,0,6,14],[7,0,7,14],[8,0,8,14],[9,0,9,14],[10,0,10,14]]}
["Fill in Blue and Orange Cells Only!"]
["APPLICATION CHECKLIST"]
["For faster application processing, please include the following items with your application:"]
["     Complete application (Project Information Tab, Customer Acknowledgment below and at least one Equipment tab."]
["     Electric account number (on Project Information tab). Attach copy of electric bill."]
["     IRS Form W-9 completed for payment recipient (available at www.irs.gov). Physical signature is required on W-9. If payment is to a contractor, customer's W-9 must also be provided."]
["     Supporting documentation to include manufacturer’s specification (cut) sheets for equipment included in this application."]
["     Customer signature and itemized proof of purchase (contractor receipts), at time of project completion. See Terms and Conditions for invoicing requirements."]
["Applications submitted for processing will be processed in the order in which they are received. Applicants will be notified as to their pre-approval status and/or any pre-inspection requirements within 10 business days from receipt of complete application. Applicants will be notified if post-installation inspections are required prior to final payment."]
[]
["CUSTOMER ACKNOWLEDGMENT"]
["For Projects Not Requiring Pre-Approval < $1,000 Incentive"]
["Authorized Representative  ",null,null,null,null,null,null,null,"Title"]
[null,null,null,null,null,null,null,null,"Date (XX/XX/XXXX)"]
[null,"By checking this box and typing my name, I hereby certify that all statements made on this application are correct to the best of my knowledge and that I have read and agree to the Terms and Conditions. Furthermore, I understand and intend that my electronic, PDF or facsimile signature be accepted and have the same force and effect as an original signature.\n\nNote: Application must include supporting documentation and copy of invoice that is dated within 60 days before application date."]
["CUSTOMER ACKNOWLEDGMENT"]
["For All Projects Requiring Pre-Approval "]
[]
["Authorized Representative  ",null,null,null,null,null,null,null,"Title"]
[null,null,null,null,null,null,null,null,"Date (XX/XX/XXXX)"]
[null,"By checking this box and typing my name, I hereby certify that all statements made on this application are correct to the best of my knowledge and that I have read and agree to the Terms and Conditions. Furthermore, I understand and intend that my electronic, PDF or facsimile signature be accepted and have the same force and effect as an original signature.\n\nNote: Upon completion of project, customer of record must sign and return the written pre-approval letter and provide invoices for all energy efficiency measures."]
["Dominion Energy South Carolina, Inc. Food Service and High Efficiency Equipment Application - Electronic                                                                                                                                                                                                                                                      Version 3.7",null,null,null,null,null,null,null,null,null,null,"Version",{"$f":"'Version Tracking'!C4","v":14.3}]

{"sheet":"Terms and Conditions","index":3,"n_rows":6,"n_cols":2,"rows_kept":6,"cut":false,"hidden":false,"merged":[[0,0,0,1],[1,0,1,1],[2,0,4,0],[2,1,4,1],[2,2,3,2]]}
["Dominion Energy South Carolina, Inc."]
["TERMS AND CONDITIONS"]
["1.  Eligibility: EnergyWise for Your Business Program (“Program”) incentives are available to non-residential electric customers for the purchase and installation of qualifying energy conservation measures (ECMs) in the Dominion Energy South Carolina service territory, subject to these Terms and Conditions (T&Cs). The process of purchasing and installing ECMs for eligible Customers pursuant to the Program is referred to herein as a “Project” or “Projects”.  Customers eligible for Rate 23  and specific large retail customers who have elected to opt out of Demand Side Management programs, by notifying us in writing using the Opt-Out form provided, are not eligible to participate. Dominion Energy South Carolina and our Program implementer (“Implementer”) (together, “We”) reserve the right to deny any application that may result in our exceeding its Program budget. Program incentives are limited, offered on a first-come/first-served basis, and are subject to Project and Customer eligibility and funds availability.  For each Program year (December 1 – November 30), Program incentive payments are capped per Customer Federal tax ID number at $100,000 per Project type.\n2. Project Types: The Program includes the following four Project types: Lighting Projects, HVAC/Motors Projects, Food Service and High Efficiency Equipment Projects, and Custom Projects. Lighting projects include Projects that use the Retrofit and New Construction Lighting worksheet.  HVAC/Motors Projects include Projects listed on the HVAC Application including Unitary HVAC, Chillers, Window Film, or Variable Frequency Drives.  Food Service and High Efficiency Equipment Projects include all cooking equipment and “plug load” equipment that is incentivized under the prescriptive Program. Restaurant cooking equipment, ice machines, vending machine and refrigeration controls, commercial washers/dryers, and lighting that may be included inside the aforementioned equipment are considered Food Service and High Efficiency Equipment Projects.  Custom Projects are Projects that can demonstrate cost effective and lasting energy efficiency and do not fall under one of the aforementioned Project types. These Projects are “custom” tailored to the Customer for each Project and cannot receive a prescriptive incentive as the savings varies widely with each Project and technology.  Strategic Energy Management, Building controls, Building Tune-ups, Whole Building Solutions, Technical Services, and new emerging technologies generally fall under this Project type.  The above examples are provided for illustrative purposes only and may not be inclusive of all Projects. \n3. Authorization, Program Changes, Suspension, or Cancellation: We may change the Program requirements, incentives or T&Cs, including suspending acceptance of applications or terminating the Program, at any time and without notice. In the event of a Program change, pre-approved applications will be processed to completion under the T&Cs in effect at time of pre-approval. Submission of a completed application does not entitle Customer to Program participation. For all Projects, entitlement to Program participation and our obligation to pay incentives may occur only after we have granted written authorization, which we may grant or not at its sole discretion.\n4.  Project Approval: Pre-approval is required for all Projects except for eligible Food Service and High-Efficiency projects with total incentives less than or equal to $1,000. For Projects not requiring pre-approval, the customer may purchase and install the qualifying equipment and submit a completed application form, supporting documentation and invoice within 60 days of the equipment’s invoice date. For Projects requiring pre-approval, we reserve the right to inspect any Project prior to pre-approval.  For Projects requiring pre-approval, no project-related ECMs may be ordered or installed prior to the date of our pre-approval. Violation of this prohibition will disqualify the ECM for incentives. Projects must be completed by the date listed on the pre-approval notification letter (within 180 calendar days for retrofit projects or one year for new construction projects).\n5. Creditworthiness: An incentive payment is conditioned upon and subject to Customer maintaining its financial creditworthiness and keeping its account in good standing.   At any time prior to an issuance of an incentive check, we may request financial information to support its financial due diligence procedures. Customer agrees to assist in this reasonable financial review.  If we believe in good faith that the Customer’s account is not in good standing, or if creditworthiness of participant has been diminished, we may reject approval of an incentive payment.  \n6.  Proof of Purchase: Prior to our verification of the ECM installation, Customer must provide copies of all invoices or other appropriate documentation that clearly verifies the costs of purchasing and installing the ECMs, including all material, labor, and equipment discounts. Invoices must indicate a verifiable breakout of all ECMs purchased for installation under the ECM incentives application, including model numbers and quantity.\n7.  Project Verification: We (or our Third-Party Evaluator “Evaluator”) may conduct an inspection of Customer’s facility to verify pre- and post-installation conditions or verify documentation prior to incentive payment at any time after receipt of an application. No warranty is expressed or implied by this verification. We are not obligated to pay any incentive until it has performed a satisfactory post-installation inspection. Should we determine that ECMs were not installed in accordance with the approved application, or if an unapproved ECM was installed, or if the installation was not consistent  with generally accepted engineering/construction practices, changes may be required before  payment is issued. Notwithstanding anything to the contrary, should we determine at any point  before payment of the incentive that there has been significant deviation in the type, amount, cost  or performance of the ECMs underlying this incentive commitment that were set forth in the  Program application and pre-approved, we retain the right to revoke this commitment or reduce the  final incentive amount accordingly. We reserve this right despite a satisfactory post-installation inspection. Customer agrees to provide prompt notice to us of any significant deviation in the type, amount, cost or performance of the ECMs underlying this incentive commitment that were set forth in the Program application and pre-approved by us.","8.  Customer Tax Obligation: Customer or Customer’s designated contractor is responsible for declaring and paying any and all applicable federal, state, and local taxes that may be owed on any incentive payment. Neither Dominion Energy South Carolina, Inc. nor any of its subsidiaries shall be liable for any federal, state, and local taxes that may be owed on or as a result of any incentive payment. The party receiving the incentive payment (Customer or Contractor) must complete IRS Form W-9 and submit it to us with the incentive application materials.  If payment is to a contractor, customer's W-9 must also be provided.\n9.  Compliance: Customer is responsible for obtaining any and all necessary licenses and permits related to the installation of ECMs. Customer also agrees to comply with all federal, state, and local laws, codes, and regulations related to the installation and disposal of all equipment.\n10.  Removal of Equipment: Customer agrees to remove and dispose of the equipment being replaced by the ECMs in accordance with all legal requirements. Customer agrees not to re-install any of this equipment in our service territory or transfer it to any other party for such installation.\n11.  Replacement of Failed Equipment: Customers who install ECMs are expected to replace any of the ECMs that fail with similar or superior energy savings equipment at Customer’s expense.\n12.  Evaluation Follow-up Visits: With advance notice, we reserve the right to make or to have its contractor(s) make follow-up visits to Customer facilities during the 36 months following completion of the project to provide us with an opportunity to review the operation of the ECMs for Program evaluation purposes. Customer agrees to cooperate with this effort.\n13.  Contractor Selection: Customer may select any contractor to perform the work contemplated by the application, even after the application is pre-approved by us. However, we reserve the right, in its sole discretion, to prohibit specific contractors from Program participation.\n14.  No Warranties: Dominion Energy South Carolina, Inc. does not endorse, guarantee, or warrant any particular manufacturer or product and we provide no warranties, express or implied, for any products or services, and herein specifically disclaims any such guarantees or warranties. We are not liable or responsible for any act or omission of any contractor hired by Customer. Customer’s reliance on warranties is limited to any warranties that may arise from, or be provided by contractors, vendors, etc. Customer acknowledges that neither Dominion Energy South Carolina, Inc. nor any of its consultants are responsible for ensuring that the design, engineering, and construction of the facility or installation of the ECMs are proper or comply with any particular laws (including patent laws), codes, regulations, or industry standards. We make no representations of any kind regarding the results to be achieved by the ECMs or the adequacy or safety of such measures.\n15.  Assumption of Risk and Limitation of Liability: Customer assumes and acknowledges all risks arising from its participation in the Program including but not limited to exposure to the novel coronavirus (“COVID-19”) and releases and discharges Dominion Energy, Inc., Dominion Energy South Carolina, its Implementer, Evaluator, and their respective officers, directors, employees and agents from any liability related thereto. Our sole obligation is limited to paying the properly qualified rebates specified herein. Neither Dominion Energy South Carolina, Inc., any of its subsidiaries, nor its Implementer or Evaluator shall be  liable to Customer or any other party for any special, indirect, consequential, or incidental damages,  regardless of the theory of recovery, caused by or arising from any activities associated with this Program.\n16.  Obligations between the Parties: Customer acknowledges that any contractor selected by Customer is not an agent, contractor, or subcontractor of Dominion Energy South Carolina and is an independent contractor engaged by Customer, and that we do not manage or control the contractor’s performance. We shall have no obligation to maintain, remove, or perform any work whatsoever on the ECMs installed. We shall have no liability for a contractor’s failure to perform, for failure of the energy savings measures to function, for any damage to Customer’s premises caused by the contractor, or for any and all damages to property or injuries to persons caused by or associated with the energy savings measures.\n17.  Miscellaneous: These T&Cs and this application, of which these T&Cs are an integral part, constitute the entire agreement between the parties and supersede all other communications, representations, and understandings."]
[]
[]
[null,{"$f":"\"Version # \"&'Version Tracking'!C4","v":"Version # 14.3"}]

{"sheet":"Technical Requirements","index":4,"n_rows":14,"n_cols":15,"rows_kept":14,"cut":false,"hidden":false,"merged":[[12,0,12,14],[13,14,13,15],[6,0,6,14],[7,0,7,14],[8,0,8,14],[9,0,9,14],[10,0,10,14],[11,0,11,14],[5,0,5,14],[0,0,0,14],[1,0,1,14],[2,0,2,14],[3,0,3,14],[4,0,4,14]]}
[]
["TECHNICAL REQUIREMENTS: HIGH-EFFICIENCY COMMERCIAL EQUIPMENT"]
["§ Only ENERGY STAR®-qualified equipment is eligible for incentives under this application. \n§ Cook and hold food cabinets are not eligible for incentives.\n§ Electric steam cookers with greater than six-pan capacity may be considered for incentives under the Custom application.\n§ Only air-cooled machines (self-contained, ice making heads or remote condensing) are eligible. Commercial ice machines with remote condensing units must be purchased with their ARI-rated cuber.\n§ Drawer cabinets, prep tables, deli cases, and open air units are not eligible for incentives.\n§ For lists of qualified products, visit:"]
["http://www.energystar.gov/products?s=mega"]
["TECHNICAL REQUIREMENTS: HIGH-EFFICIENCY REFRIGERATION COMPONENTS"]
["§ Anti-sweat heater controls must sense the relative humidity or dew point of the surrounding air to control glass door or frame anti-sweat heaters."]
["§ The replacement unit must be an Electronically Commutated Motor, which is a brushless DC motor that operates more efficiently than standard electro-mechanical\nrefrigeration fan motors. Electronically Commutated Motor fan motors must replace an existing standard-efficiency shaded-pole evaporator or permanent split\ncapacitor fan motor in refrigerated walk-in, reach-in, or display boxes (coolers or freezers)."]
["§    Refrigeration night covers must be applied for a minimum of six hours per day to qualify for incentives. Covers may be applied to medium- or low-temperature open cases of horizontal or vertical configuration."]
["§ LED refrigerated case lighting must be installed as a retrofit measure to replace existing linear fluorescent case lighting. To qualify for incentives, the existing ballast and lampholders must be permanently removed and replaced with an LED refrigeration retrofit kit certified by a Nationally Recognized Testing Laboratory (NRTL). Existing wiring may be reused, if necessary."]
["§ LED refrigerated case lighting controls may be installed for stand-alone or aisle refrigerated cases."]
["TECHNICAL REQUIREMENTS: RECEPTACLE LOAD CONTROLS"]
["§ Vending machine controls may be installed to de-energize machines when the facility is not occupied. Controls must include a passive infrared sensor to turn off\nlighting. For refrigerated machines, controls must be able to cycle the compressor to maintain products at a maximum desired temperature."]
["§    Personal receptacle occupancy sensors may be installed in open, private or common areas of office facilities. Controls must include a passive infrared occupancy\nsensor and connected power strip. The power strip must be able to maintain constant power for selected loads. To qualify for incentives, provide information on\naverage connected load per sensor. Suggested loads include task lighting, personal printers, monitors, and related equipment."]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"\"Version \" & 'Version Tracking'!C4","v":"Version 14.3"}]

{"sheet":"Equipment Incentives","index":5,"n_rows":71,"n_cols":4,"rows_kept":71,"cut":false,"hidden":false,"merged":[[52,0,55,0],[52,1,53,1],[57,0,68,0],[59,1,62,1],[32,0,50,0],[32,1,35,1],[37,1,40,1],[42,1,45,1],[47,1,50,1],[20,0,26,0],[20,1,22,1],[24,1,26,1],[28,0,30,0],[0,1,0,3],[1,1,1,3],[3,0,18,0],[3,1,6,1],[8,1,10,1]]}
[null,"Dominion Energy South Carolina, Inc. "]
[null,"EQUIPMENT MEASURES AND INCENTIVES"]
[null,"Proposed\nMeasure","Measure Type","Incentive/ Unit"]
["HE Food Prep","Steam Cookers","3 Pan",800]
[null,null,"4 Pan",800]
[null,null,"5 Pan",1200]
[null,null,"6 Pan",1200]
[]
[null,"Insulated Hot Holding Cabinets","Half Size: 0 < V < 13",300]
[null,null,"3/4 Size: 13 ≤ V < 28 ",400]
[null,null,"Full Size: 28 ≤ V",500]
[]
[null,"High-Efficiency Electric Fryers","Large Vat","$300/Vat"]
[]
[null,"Electric Griddles","All",300]
[]
[null,"High-Efficiency Electric Convection Ovens","All","$400/oven"]
[]
[null,"High-Efficiency Electric Combination Ovens","All",1000]
[]
["Ice Machines","Ice Machine - Batch","Ice Making Head",150]
[null,null,"Split System",100]
[null,null,"Self-Contained",50]
[]
[null,"Ice Machine - Continuous","Ice Making Head",125]
[null,null,"Split System",150]
[null,null,"Self-Contained",75]
[]
["Clothes\nWashers","Commercial Clothes Washers","Electric Water Heater",50]
[]
[null,"Commercial Clothes Washers","Non-Electric Water Heater",50]
[]
["Refrig & Freezers","Commercial Reach-in\nRefrigerators","V < 15 cubic feet",20]
[null,null,"15 ≤ V < 30 cubic feet",30]
[null,null,"30 ≤ V < 50 cubic feet",50]
[null,null,"V ≥ 50 cubic feet",100]
[]
[null,"Commercial Glass Door Reach-in\nRefrigerators","V < 15 cubic feet",55]
[null,null,"15 ≤ V < 30 cubic feet",55]
[null,null,"30 ≤ V < 50 cubic feet",75]
[null,null,"V ≥ 50 cubic feet",100]
[]
[null,"Commercial Reach-in\nFreezers","V < 15 cubic feet",50]
[null,null,"15 ≤ V < 30 cubic feet",75]
[null,null,"30 ≤ V < 50 cubic feet",125]
[null,null,"V ≥ 50 cubic feet",175]
[]
[null,"Commercial Glass-Door Reach-in\nFreezers","V < 15 cubic feet",75]
[null,null,"15 ≤ V < 30 cubic feet",100]
[null,null,"30 ≤ V < 50 cubic feet",150]
[null,null,"V ≥ 50 cubic feet",200]
[]
["Receptacle Load\nControls","Vending Machine Controls\n(Vending Misers)","Refrigerated",20]
[null,null,"Non-Refrigerated",10]
[]
[null,"Personal Receptacle\nOccupancy Sensors\n(Cubicle Controls)","Power Strip with Occupancy Sensor","$5/control"]
[]
["HE Refrig Components","Anti-Sweat Heater Controls","Cooler/Freezer Doors","$50/door"]
[]
[null,"Electronically Commutated Motors \n(Walk-in, Reach-in, \nand Display Coolers/Freezers)","Walk-in Cooler/Freezer Replacing Shaded Pole","$100/motor"]
[null,null,"Walk-in Cooler/Freezer Replacing PSC Motor","$50/motor"]
[null,null,"Reach-in Cooler/Freezer","$35/motor"]
[null,null,"Display Cooler/Freezer","$35/motor"]
[]
[null,"Refrigeration Night Covers","Linear Feet (Freezers/Coolers)","$5/foot"]
[]
[null,"LED Refrigerated Case Lighting","Coolers / Freezers","$25/door"]
[]
[null,"LED Refrigerated Case Lighting Controls","All","$5/door"]
[]
[null,null,null,{"$f":"\"Version \" & 'Version Tracking'!C4","v":"Version 14.3"}]

{"sheet":"Equipment Input Instructions","index":6,"n_rows":19,"n_cols":8,"rows_kept":19,"cut":false,"hidden":false,"merged":[[11,2,11,6],[12,2,12,6],[13,2,13,6],[14,2,14,6],[18,7,18,8],[1,1,1,7],[2,1,2,7],[3,1,3,7],[4,1,4,7],[5,1,5,7]]}
[]
[]
[]
[]
[null,"Food Service High Efficiency Equipment"]
[]
[null,null,null,"Copyright © 2015 ICF Resources, LLC, All Rights Reserved. Do not copy, distribute or quote without ICF’s written permission."]
[]
[null,null,"Instructions"]
[null,null,"On the Equipment Input Tab, fill out all the blue shaded cells. "]
[]
[null,null,"1. Read Technical Requirements tab and Equipment Incentives tab for detailed information on equipment requirements and eligibility."]
[null,null,"2. Select Measure Type, then select Type/Size, then enter make, model and quantity of equipment being applied for in blue shaded areas of\n     Equipment Input tab."]
[null,null,"3. Measure Summary tab will be automatically populated based on Equipment Input tab entries."]
[null,null,"4. Application packages must be submitted by email."]
[null,null,null,"Email Address:"]
[null,null,null,"EnergyExperts@SC.DominionEnergyAccount.com"]
[]
[null,null,null,null,null,null,null,{"$f":"\"Version \" & 'Version Tracking'!C4","v":"Version 14.3"}]

{"sheet":"Equipment Input","index":7,"n_rows":42,"n_cols":21,"rows_kept":42,"cut":false,"hidden":false,"merged":[[8,15,8,17],[18,14,18,20],[19,8,19,9],[10,8,10,9],[11,8,11,9],[12,8,12,9],[18,2,18,12],[15,1,16,1],[8,1,8,6],[10,3,10,4],[11,3,11,4],[12,3,12,4],[13,3,13,4],[1,1,1,12],[2,1,2,12],[3,1,3,12],[4,1,4,12],[5,1,5,12]]}
[]
[]
[]
[null,"C&I Prescriptive - Food Service & \nHigh-Efficiency Equipment"]
[null,{"$f":"\"Version # \"&'Version Tracking'!C4","v":"Version # 14.3"}]
[null," "]
[null,"Copyright © 2023 ICF Resources, LLC, All Rights Reserved. Do not copy, distribute or quote without ICF’s written permission."]
[]
[null,"Required General Project Information",null,null,null,null,null,"Administrative Use Only",null,null,null,null,null,null,null,"Summary Table"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Total kWh ","Total Summer Coincident Peak (kW)","Total Incentive"]
[null,null,"Project Name",null,null,"Prepared By",null,"Project ID",null,null,null,null,null,null,null,{"$f":"SUM(O23:O42,P23:P42,Q23:Q42)","v":0},{"$f":"SUM(R23:R42,S23:S42,T23:T42)","v":0},{"$f":"SUM(U23:U42)","v":0}]
[null,null,"Project Address",null,null,"Contact Person",null,"Data Input By"]
[null,null,"City",null,null,"Phone",null,"Input Date"]
[null,null,"ZIP",null,null,"Email"]
[]
[null,"Input Cells"]
[null,null,"Data input allowed in blue shaded cells only.",null,null,null,null,"*If print button malfunctions, "]
[null,null,null,null,null,null,null,"select printer settings manually from print menu"]
[null,null,"Food Service & High-Efficiency Equipment",null,null,null,null,null,null,null,null,null,null,"Incentives","Savings"]
[null,"Line Item","Building Type","Measure Type","Type/Size","Make","Model","For Holding Cabinets Enter Vol (ft3)","For Refrigerated Case Lighting Upgrades Enter the Proposed and Existing Bulb Wattage",null,"For Refrigerated Case Lighting Controls Measure Enter the Lighting Wattage controlled ","Quantity","Units of Quantity","Incentive Requested","kWh Saved","kWh Saved for Refrigerated Case Lighting Measure","kWh Saved for Refrigerated Case Lighting Control Measure","Summer Coincident Peak kW Saved","Summer Coincident Peak kW Saved For Refrigerated Case Lighting Measure","Summer Coincident Peak kW Saved For Refrigerated Case Lighting Control Measure","Incentive"]
[null,null,null,null,null,null,null,null,"Proposed","Existing"]
[null,"Ex.","Office","ECM (Coolers/Freezers)","Walk-in Cooler replacing Shaded Poll",null,null,null,null,null,null,1,{"$f":"IF(D22=\"\",\"\",VLOOKUP(D22,Lookups!$D$3:$E$30,2,0))","v":"Units"},{"$f":"IF(OR(D22=\"\",E22=\"\"),\"\",VLOOKUP($D22&\"_\"&$E22,Lookups!$J$3:$M$83,2,0)*$L22)","v":100},{"$f":"IF(OR(D22=\"\",E22=\"\"),\"\",VLOOKUP($D22&\"_\"&$E22,Lookups!$J$3:$M$83,3,0)*$L22)","v":1016},null,null,{"$f":"IF(OR(D22=\"\",E22=\"\"),\"\",VLOOKUP($D22&\"_\"&$E22,Lookups!$J$3:$M$83,4,0)*$L22)","v":0.12},null,null,{"$f":"$N22","v":100}]
[null,1,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D23=\"\",\"\",VLOOKUP(D23,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D23=\"\",E23=\"\"),\"\",VLOOKUP($D23&\"_\"&$E23,Lookups!$J$3:$M$83,2,0)*$L23)","v":""},{"$f":"IF(OR(D23=\"\",E23=\"\", D23=\"LED Refrig Case Lighting\",D23=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D23=\"Hot Holding Cabinets\",E23=\"Half Size\"),Lookups!L7*L23,IF(AND(D23=\"Hot Holding Cabinets\",E23=\"3/4 Size\"),Lookups!L17*L23,IF(AND(D23=\"Hot Holding Cabinets\",E23=\"Full Size\"),Lookups!L27*L23,VLOOKUP($D23&\"_\"&$E23,Lookups!$J$3:$M$83,3,0)*$L23))))","v":""},{"$f":"IF(AND(D23=\"LED Refrig Case Lighting\",E23=\"Coolers\"),(((J23-I23)*8766*1.41)/1000)*L23,IF(AND(D23=\"LED Refrig Case Lighting\",E23=\"Freezers\"),(((J23-I23)*8766*1.52)/1000)*L23,\"\"))","v":""},{"$f":"IF(AND(D23=\"LED Refrig Case Lighting Controls\",E23=\"Coolers\"),((K23*8766*1.25*0.43)/1000)*L23,IF(AND(D23=\"LED Refrig Case Lighting Controls\",E23=\"Freezers\"),((K23*8766*1.3*0.43)/1000)*L23,\"\"))","v":""},{"$f":"IF(OR(D23=\"\",E23=\"\", D23=\"LED Refrig Case Lighting\",D23=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D23=\"Hot Holding Cabinets\",E23=\"Half Size\"),Lookups!M7*L23,IF(AND(D23=\"Hot Holding Cabinets\",E23=\"3/4 Size\"),Lookups!M17*L23,IF(AND(D23=\"Hot Holding Cabinets\",E23=\"Full Size\"),Lookups!M27*L23,VLOOKUP($D23&\"_\"&$E23,Lookups!$J$3:$M$83,4,0)*$L23))))","v":""},{"$f":"IF(AND(D23=\"LED Refrig Case Lighting\",E23=\"Coolers\"),(((J23-I23)*0.95*1.4)/1000)*L23,IF(AND(D23=\"LED Refrig Case Lighting\",E23=\"Freezers\"),(((J23-I23)*0.95*1.51)/1000)*L23,\"\"))","v":""},{"$f":"IF(AND(D23=\"LED Refrig Case Lighting Controls\",E23=\"Coolers\"),((K23*0.95*1.25*0.43)/1000)*L23,IF(AND(D23=\"LED Refrig Case Lighting Controls\",E23=\"Freezers\"),((K23*0.95*1.3*0.43)/1000)*L23,\"\"))","v":""}]
[null,2,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D24=\"\",\"\",VLOOKUP(D24,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D24=\"\",E24=\"\"),\"\",VLOOKUP($D24&\"_\"&$E24,Lookups!$J$3:$M$83,2,0)*$L24)","v":""},{"$f":"IF(OR(D24=\"\",E24=\"\", D24=\"LED Refrig Case Lighting\",D24=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D24=\"Hot Holding Cabinets\",E24=\"Half Size\"),Lookups!L8*L24,IF(AND(D24=\"Hot Holding Cabinets\",E24=\"3/4 Size\"),Lookups!L18*L24,IF(AND(D24=\"Hot Holding Cabinets\",E24=\"Full Size\"),Lookups!L28*L24,VLOOKUP($D24&\"_\"&$E24,Lookups!$J$3:$M$83,3,0)*$L24))))","v":""},{"$f":"IF(AND(D24=\"LED Refrig Case Lighting\",E24=\"Coolers\"),(((J24-I24)*8766*1.41)/1000)*L24,IF(AND(D24=\"LED Refrig Case Lighting\",E24=\"Freezers\"),(((J24-I24)*8766*1.52)/1000)*L24,\"\"))","v":""},{"$f":"IF(AND(D24=\"LED Refrig Case Lighting Controls\",E24=\"Coolers\"),((K24*8766*1.25*0.43)/1000)*L24,IF(AND(D24=\"LED Refrig Case Lighting Controls\",E24=\"Freezers\"),((K24*8766*1.3*0.43)/1000)*L24,\"\"))","v":""},{"$f":"IF(OR(D24=\"\",E24=\"\", D24=\"LED Refrig Case Lighting\",D24=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D24=\"Hot Holding Cabinets\",E24=\"Half Size\"),Lookups!M8*L24,IF(AND(D24=\"Hot Holding Cabinets\",E24=\"3/4 Size\"),Lookups!M18*L24,IF(AND(D24=\"Hot Holding Cabinets\",E24=\"Full Size\"),Lookups!M28*L24,VLOOKUP($D24&\"_\"&$E24,Lookups!$J$3:$M$83,4,0)*$L24))))","v":""},{"$f":"IF(AND(D24=\"LED Refrig Case Lighting\",E24=\"Coolers\"),(((J24-I24)*0.95*1.4)/1000)*L24,IF(AND(D24=\"LED Refrig Case Lighting\",E24=\"Freezers\"),(((J24-I24)*0.95*1.51)/1000)*L24,\"\"))","v":""},{"$f":"IF(AND(D24=\"LED Refrig Case Lighting Controls\",E24=\"Coolers\"),((K24*0.95*1.25*0.43)/1000)*L24,IF(AND(D24=\"LED Refrig Case Lighting Controls\",E24=\"Freezers\"),((K24*0.95*1.3*0.43)/1000)*L24,\"\"))","v":""}]
[null,3,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D25=\"\",\"\",VLOOKUP(D25,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D25=\"\",E25=\"\"),\"\",VLOOKUP($D25&\"_\"&$E25,Lookups!$J$3:$M$83,2,0)*$L25)","v":""},{"$f":"IF(OR(D25=\"\",E25=\"\", D25=\"LED Refrig Case Lighting\",D25=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D25=\"Hot Holding Cabinets\",E25=\"Half Size\"),Lookups!L9*L25,IF(AND(D25=\"Hot Holding Cabinets\",E25=\"3/4 Size\"),Lookups!L19*L25,IF(AND(D25=\"Hot Holding Cabinets\",E25=\"Full Size\"),Lookups!L29*L25,VLOOKUP($D25&\"_\"&$E25,Lookups!$J$3:$M$83,3,0)*$L25))))","v":""},"","",{"$f":"IF(OR(D25=\"\",E25=\"\", D25=\"LED Refrig Case Lighting\",D25=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D25=\"Hot Holding Cabinets\",E25=\"Half Size\"),Lookups!M9*L25,IF(AND(D25=\"Hot Holding Cabinets\",E25=\"3/4 Size\"),Lookups!M19*L25,IF(AND(D25=\"Hot Holding Cabinets\",E25=\"Full Size\"),Lookups!M29*L25,VLOOKUP($D25&\"_\"&$E25,Lookups!$J$3:$M$83,4,0)*$L25))))","v":""},"",""]
[null,4,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D26=\"\",\"\",VLOOKUP(D26,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D26=\"\",E26=\"\"),\"\",VLOOKUP($D26&\"_\"&$E26,Lookups!$J$3:$M$83,2,0)*$L26)","v":""},{"$f":"IF(OR(D26=\"\",E26=\"\", D26=\"LED Refrig Case Lighting\",D26=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D26=\"Hot Holding Cabinets\",E26=\"Half Size\"),Lookups!L10*L26,IF(AND(D26=\"Hot Holding Cabinets\",E26=\"3/4 Size\"),Lookups!L20*L26,IF(AND(D26=\"Hot Holding Cabinets\",E26=\"Full Size\"),Lookups!L30*L26,VLOOKUP($D26&\"_\"&$E26,Lookups!$J$3:$M$83,3,0)*$L26))))","v":""},"","",{"$f":"IF(OR(D26=\"\",E26=\"\", D26=\"LED Refrig Case Lighting\",D26=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D26=\"Hot Holding Cabinets\",E26=\"Half Size\"),Lookups!M10*L26,IF(AND(D26=\"Hot Holding Cabinets\",E26=\"3/4 Size\"),Lookups!M20*L26,IF(AND(D26=\"Hot Holding Cabinets\",E26=\"Full Size\"),Lookups!M30*L26,VLOOKUP($D26&\"_\"&$E26,Lookups!$J$3:$M$83,4,0)*$L26))))","v":""},"",""]
[null,5,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D27=\"\",\"\",VLOOKUP(D27,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D27=\"\",E27=\"\"),\"\",VLOOKUP($D27&\"_\"&$E27,Lookups!$J$3:$M$83,2,0)*$L27)","v":""},{"$f":"IF(OR(D27=\"\",E27=\"\", D27=\"LED Refrig Case Lighting\",D27=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D27=\"Hot Holding Cabinets\",E27=\"Half Size\"),Lookups!L11*L27,IF(AND(D27=\"Hot Holding Cabinets\",E27=\"3/4 Size\"),Lookups!L21*L27,IF(AND(D27=\"Hot Holding Cabinets\",E27=\"Full Size\"),Lookups!L31*L27,VLOOKUP($D27&\"_\"&$E27,Lookups!$J$3:$M$83,3,0)*$L27))))","v":""},"","",{"$f":"IF(OR(D27=\"\",E27=\"\", D27=\"LED Refrig Case Lighting\",D27=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D27=\"Hot Holding Cabinets\",E27=\"Half Size\"),Lookups!M11*L27,IF(AND(D27=\"Hot Holding Cabinets\",E27=\"3/4 Size\"),Lookups!M21*L27,IF(AND(D27=\"Hot Holding Cabinets\",E27=\"Full Size\"),Lookups!M31*L27,VLOOKUP($D27&\"_\"&$E27,Lookups!$J$3:$M$83,4,0)*$L27))))","v":""},"",""]
[null,6,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D28=\"\",E28=\"\"),\"\",VLOOKUP($D28&\"_\"&$E28,Lookups!$J$3:$M$83,2,0)*$L28)","v":""},{"$f":"IF(OR(D28=\"\",E28=\"\", D28=\"LED Refrig Case Lighting\",D28=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D28=\"Hot Holding Cabinets\",E28=\"Half Size\"),Lookups!L12*L28,IF(AND(D28=\"Hot Holding Cabinets\",E28=\"3/4 Size\"),Lookups!L22*L28,IF(AND(D28=\"Hot Holding Cabinets\",E28=\"Full Size\"),Lookups!L32*L28,VLOOKUP($D28&\"_\"&$E28,Lookups!$J$3:$M$83,3,0)*$L28))))","v":""},"","",{"$f":"IF(OR(D28=\"\",E28=\"\", D28=\"LED Refrig Case Lighting\",D28=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D28=\"Hot Holding Cabinets\",E28=\"Half Size\"),Lookups!M12*L28,IF(AND(D28=\"Hot Holding Cabinets\",E28=\"3/4 Size\"),Lookups!M22*L28,IF(AND(D28=\"Hot Holding Cabinets\",E28=\"Full Size\"),Lookups!M32*L28,VLOOKUP($D28&\"_\"&$E28,Lookups!$J$3:$M$83,4,0)*$L28))))","v":""},"",""]
[null,7,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D29=\"\",E29=\"\"),\"\",VLOOKUP($D29&\"_\"&$E29,Lookups!$J$3:$M$83,2,0)*$L29)","v":""},{"$f":"IF(OR(D29=\"\",E29=\"\", D29=\"LED Refrig Case Lighting\",D29=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D29=\"Hot Holding Cabinets\",E29=\"Half Size\"),Lookups!L13*L29,IF(AND(D29=\"Hot Holding Cabinets\",E29=\"3/4 Size\"),Lookups!L23*L29,IF(AND(D29=\"Hot Holding Cabinets\",E29=\"Full Size\"),Lookups!L33*L29,VLOOKUP($D29&\"_\"&$E29,Lookups!$J$3:$M$83,3,0)*$L29))))","v":""},"","",{"$f":"IF(OR(D29=\"\",E29=\"\", D29=\"LED Refrig Case Lighting\",D29=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D29=\"Hot Holding Cabinets\",E29=\"Half Size\"),Lookups!M13*L29,IF(AND(D29=\"Hot Holding Cabinets\",E29=\"3/4 Size\"),Lookups!M23*L29,IF(AND(D29=\"Hot Holding Cabinets\",E29=\"Full Size\"),Lookups!M33*L29,VLOOKUP($D29&\"_\"&$E29,Lookups!$J$3:$M$83,4,0)*$L29))))","v":""},"",""]
[null,8,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D30=\"\",E30=\"\"),\"\",VLOOKUP($D30&\"_\"&$E30,Lookups!$J$3:$M$83,2,0)*$L30)","v":""},{"$f":"IF(OR(D30=\"\",E30=\"\", D30=\"LED Refrig Case Lighting\",D30=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D30=\"Hot Holding Cabinets\",E30=\"Half Size\"),Lookups!L14*L30,IF(AND(D30=\"Hot Holding Cabinets\",E30=\"3/4 Size\"),Lookups!L24*L30,IF(AND(D30=\"Hot Holding Cabinets\",E30=\"Full Size\"),Lookups!L34*L30,VLOOKUP($D30&\"_\"&$E30,Lookups!$J$3:$M$83,3,0)*$L30))))","v":""},"","",{"$f":"IF(OR(D30=\"\",E30=\"\", D30=\"LED Refrig Case Lighting\",D30=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D30=\"Hot Holding Cabinets\",E30=\"Half Size\"),Lookups!M14*L30,IF(AND(D30=\"Hot Holding Cabinets\",E30=\"3/4 Size\"),Lookups!M24*L30,IF(AND(D30=\"Hot Holding Cabinets\",E30=\"Full Size\"),Lookups!M34*L30,VLOOKUP($D30&\"_\"&$E30,Lookups!$J$3:$M$83,4,0)*$L30))))","v":""},"",""]
[null,9,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D31=\"\",E31=\"\"),\"\",VLOOKUP($D31&\"_\"&$E31,Lookups!$J$3:$M$83,2,0)*$L31)","v":""},{"$f":"IF(OR(D31=\"\",E31=\"\", D31=\"LED Refrig Case Lighting\",D31=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D31=\"Hot Holding Cabinets\",E31=\"Half Size\"),Lookups!L15*L31,IF(AND(D31=\"Hot Holding Cabinets\",E31=\"3/4 Size\"),Lookups!L25*L31,IF(AND(D31=\"Hot Holding Cabinets\",E31=\"Full Size\"),Lookups!L35*L31,VLOOKUP($D31&\"_\"&$E31,Lookups!$J$3:$M$83,3,0)*$L31))))","v":""},"","",{"$f":"IF(OR(D31=\"\",E31=\"\", D31=\"LED Refrig Case Lighting\",D31=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D31=\"Hot Holding Cabinets\",E31=\"Half Size\"),Lookups!M15*L31,IF(AND(D31=\"Hot Holding Cabinets\",E31=\"3/4 Size\"),Lookups!M25*L31,IF(AND(D31=\"Hot Holding Cabinets\",E31=\"Full Size\"),Lookups!M35*L31,VLOOKUP($D31&\"_\"&$E31,Lookups!$J$3:$M$83,4,0)*$L31))))","v":""},"",""]
[null,10,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D32=\"\",E32=\"\"),\"\",VLOOKUP($D32&\"_\"&$E32,Lookups!$J$3:$M$83,2,0)*$L32)","v":""},{"$f":"IF(OR(D32=\"\",E32=\"\", D32=\"LED Refrig Case Lighting\",D32=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D32=\"Hot Holding Cabinets\",E32=\"Half Size\"),Lookups!L16*L32,IF(AND(D32=\"Hot Holding Cabinets\",E32=\"3/4 Size\"),Lookups!L26*L32,IF(AND(D32=\"Hot Holding Cabinets\",E32=\"Full Size\"),Lookups!L36*L32,VLOOKUP($D32&\"_\"&$E32,Lookups!$J$3:$M$83,3,0)*$L32))))","v":""},"","",{"$f":"IF(OR(D32=\"\",E32=\"\", D32=\"LED Refrig Case Lighting\",D32=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D32=\"Hot Holding Cabinets\",E32=\"Half Size\"),Lookups!M16*L32,IF(AND(D32=\"Hot Holding Cabinets\",E32=\"3/4 Size\"),Lookups!M26*L32,IF(AND(D32=\"Hot Holding Cabinets\",E32=\"Full Size\"),Lookups!M36*L32,VLOOKUP($D32&\"_\"&$E32,Lookups!$J$3:$M$83,4,0)*$L32))))","v":""},"",""]
[null,11,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D33=\"\",E33=\"\"),\"\",VLOOKUP($D33&\"_\"&$E33,Lookups!$J$3:$M$83,2,0)*$L33)","v":""},{"$f":"IF(OR(D33=\"\",E33=\"\", D33=\"LED Refrig Case Lighting\",D33=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D33=\"Hot Holding Cabinets\",E33=\"Half Size\"),Lookups!L17*L33,IF(AND(D33=\"Hot Holding Cabinets\",E33=\"3/4 Size\"),Lookups!L27*L33,IF(AND(D33=\"Hot Holding Cabinets\",E33=\"Full Size\"),Lookups!L37*L33,VLOOKUP($D33&\"_\"&$E33,Lookups!$J$3:$M$83,3,0)*$L33))))","v":""},"","",{"$f":"IF(OR(D33=\"\",E33=\"\", D33=\"LED Refrig Case Lighting\",D33=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D33=\"Hot Holding Cabinets\",E33=\"Half Size\"),Lookups!M17*L33,IF(AND(D33=\"Hot Holding Cabinets\",E33=\"3/4 Size\"),Lookups!M27*L33,IF(AND(D33=\"Hot Holding Cabinets\",E33=\"Full Size\"),Lookups!M37*L33,VLOOKUP($D33&\"_\"&$E33,Lookups!$J$3:$M$83,4,0)*$L33))))","v":""},"",""]
[null,12,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D34=\"\",E34=\"\"),\"\",VLOOKUP($D34&\"_\"&$E34,Lookups!$J$3:$M$83,2,0)*$L34)","v":""},{"$f":"IF(OR(D34=\"\",E34=\"\", D34=\"LED Refrig Case Lighting\",D34=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D34=\"Hot Holding Cabinets\",E34=\"Half Size\"),Lookups!L18*L34,IF(AND(D34=\"Hot Holding Cabinets\",E34=\"3/4 Size\"),Lookups!L28*L34,IF(AND(D34=\"Hot Holding Cabinets\",E34=\"Full Size\"),Lookups!L38*L34,VLOOKUP($D34&\"_\"&$E34,Lookups!$J$3:$M$83,3,0)*$L34))))","v":""},"","",{"$f":"IF(OR(D34=\"\",E34=\"\", D34=\"LED Refrig Case Lighting\",D34=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D34=\"Hot Holding Cabinets\",E34=\"Half Size\"),Lookups!M18*L34,IF(AND(D34=\"Hot Holding Cabinets\",E34=\"3/4 Size\"),Lookups!M28*L34,IF(AND(D34=\"Hot Holding Cabinets\",E34=\"Full Size\"),Lookups!M38*L34,VLOOKUP($D34&\"_\"&$E34,Lookups!$J$3:$M$83,4,0)*$L34))))","v":""},"",""]
[null,13,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D35=\"\",\"\",VLOOKUP(D35,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D35=\"\",E35=\"\"),\"\",VLOOKUP($D35&\"_\"&$E35,Lookups!$J$3:$M$83,2,0)*$L35)","v":""},{"$f":"IF(OR(D35=\"\",E35=\"\", D35=\"LED Refrig Case Lighting\",D35=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D35=\"Hot Holding Cabinets\",E35=\"Half Size\"),Lookups!L19*L35,IF(AND(D35=\"Hot Holding Cabinets\",E35=\"3/4 Size\"),Lookups!L29*L35,IF(AND(D35=\"Hot Holding Cabinets\",E35=\"Full Size\"),Lookups!L39*L35,VLOOKUP($D35&\"_\"&$E35,Lookups!$J$3:$M$83,3,0)*$L35))))","v":""},"","",{"$f":"IF(OR(D35=\"\",E35=\"\", D35=\"LED Refrig Case Lighting\",D35=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D35=\"Hot Holding Cabinets\",E35=\"Half Size\"),Lookups!M19*L35,IF(AND(D35=\"Hot Holding Cabinets\",E35=\"3/4 Size\"),Lookups!M29*L35,IF(AND(D35=\"Hot Holding Cabinets\",E35=\"Full Size\"),Lookups!M39*L35,VLOOKUP($D35&\"_\"&$E35,Lookups!$J$3:$M$83,4,0)*$L35))))","v":""},"",""]
[null,14,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D36=\"\",E36=\"\"),\"\",VLOOKUP($D36&\"_\"&$E36,Lookups!$J$3:$M$83,2,0)*$L36)","v":""},{"$f":"IF(OR(D36=\"\",E36=\"\", D36=\"LED Refrig Case Lighting\",D36=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D36=\"Hot Holding Cabinets\",E36=\"Half Size\"),Lookups!L20*L36,IF(AND(D36=\"Hot Holding Cabinets\",E36=\"3/4 Size\"),Lookups!L30*L36,IF(AND(D36=\"Hot Holding Cabinets\",E36=\"Full Size\"),Lookups!L40*L36,VLOOKUP($D36&\"_\"&$E36,Lookups!$J$3:$M$83,3,0)*$L36))))","v":""},"","",{"$f":"IF(OR(D36=\"\",E36=\"\", D36=\"LED Refrig Case Lighting\",D36=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D36=\"Hot Holding Cabinets\",E36=\"Half Size\"),Lookups!M20*L36,IF(AND(D36=\"Hot Holding Cabinets\",E36=\"3/4 Size\"),Lookups!M30*L36,IF(AND(D36=\"Hot Holding Cabinets\",E36=\"Full Size\"),Lookups!M40*L36,VLOOKUP($D36&\"_\"&$E36,Lookups!$J$3:$M$83,4,0)*$L36))))","v":""},"",""]
[null,15,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D37=\"\",E37=\"\"),\"\",VLOOKUP($D37&\"_\"&$E37,Lookups!$J$3:$M$83,2,0)*$L37)","v":""},{"$f":"IF(OR(D37=\"\",E37=\"\", D37=\"LED Refrig Case Lighting\",D37=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D37=\"Hot Holding Cabinets\",E37=\"Half Size\"),Lookups!L21*L37,IF(AND(D37=\"Hot Holding Cabinets\",E37=\"3/4 Size\"),Lookups!L31*L37,IF(AND(D37=\"Hot Holding Cabinets\",E37=\"Full Size\"),Lookups!L41*L37,VLOOKUP($D37&\"_\"&$E37,Lookups!$J$3:$M$83,3,0)*$L37))))","v":""},"","",{"$f":"IF(OR(D37=\"\",E37=\"\", D37=\"LED Refrig Case Lighting\",D37=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D37=\"Hot Holding Cabinets\",E37=\"Half Size\"),Lookups!M21*L37,IF(AND(D37=\"Hot Holding Cabinets\",E37=\"3/4 Size\"),Lookups!M31*L37,IF(AND(D37=\"Hot Holding Cabinets\",E37=\"Full Size\"),Lookups!M41*L37,VLOOKUP($D37&\"_\"&$E37,Lookups!$J$3:$M$83,4,0)*$L37))))","v":""},"",""]
[null,16,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(D38=\"\",E38=\"\"),\"\",VLOOKUP($D38&\"_\"&$E38,Lookups!$J$3:$M$83,2,0)*$L38)","v":""},{"$f":"IF(OR(D38=\"\",E38=\"\", D38=\"LED Refrig Case Lighting\",D38=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D38=\"Hot Holding Cabinets\",E38=\"Half Size\"),Lookups!L22*L38,IF(AND(D38=\"Hot Holding Cabinets\",E38=\"3/4 Size\"),Lookups!L32*L38,IF(AND(D38=\"Hot Holding Cabinets\",E38=\"Full Size\"),Lookups!L42*L38,VLOOKUP($D38&\"_\"&$E38,Lookups!$J$3:$M$83,3,0)*$L38))))","v":""},"","",{"$f":"IF(OR(D38=\"\",E38=\"\", D38=\"LED Refrig Case Lighting\",D38=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D38=\"Hot Holding Cabinets\",E38=\"Half Size\"),Lookups!M22*L38,IF(AND(D38=\"Hot Holding Cabinets\",E38=\"3/4 Size\"),Lookups!M32*L38,IF(AND(D38=\"Hot Holding Cabinets\",E38=\"Full Size\"),Lookups!M42*L38,VLOOKUP($D38&\"_\"&$E38,Lookups!$J$3:$M$83,4,0)*$L38))))","v":""},"",""]
[null,17,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D39=\"\",\"\",VLOOKUP(D39,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D39=\"\",E39=\"\"),\"\",VLOOKUP($D39&\"_\"&$E39,Lookups!$J$3:$M$83,2,0)*$L39)","v":""},{"$f":"IF(OR(D39=\"\",E39=\"\", D39=\"LED Refrig Case Lighting\",D39=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D39=\"Hot Holding Cabinets\",E39=\"Half Size\"),Lookups!L23*L39,IF(AND(D39=\"Hot Holding Cabinets\",E39=\"3/4 Size\"),Lookups!L33*L39,IF(AND(D39=\"Hot Holding Cabinets\",E39=\"Full Size\"),Lookups!L43*L39,VLOOKUP($D39&\"_\"&$E39,Lookups!$J$3:$M$83,3,0)*$L39))))","v":""},"","",{"$f":"IF(OR(D39=\"\",E39=\"\", D39=\"LED Refrig Case Lighting\",D39=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D39=\"Hot Holding Cabinets\",E39=\"Half Size\"),Lookups!M23*L39,IF(AND(D39=\"Hot Holding Cabinets\",E39=\"3/4 Size\"),Lookups!M33*L39,IF(AND(D39=\"Hot Holding Cabinets\",E39=\"Full Size\"),Lookups!M43*L39,VLOOKUP($D39&\"_\"&$E39,Lookups!$J$3:$M$83,4,0)*$L39))))","v":""},"",""]
[null,18,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D40=\"\",\"\",VLOOKUP(D40,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D40=\"\",E40=\"\"),\"\",VLOOKUP($D40&\"_\"&$E40,Lookups!$J$3:$M$83,2,0)*$L40)","v":""},{"$f":"IF(OR(D40=\"\",E40=\"\", D40=\"LED Refrig Case Lighting\",D40=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D40=\"Hot Holding Cabinets\",E40=\"Half Size\"),Lookups!L24*L40,IF(AND(D40=\"Hot Holding Cabinets\",E40=\"3/4 Size\"),Lookups!L34*L40,IF(AND(D40=\"Hot Holding Cabinets\",E40=\"Full Size\"),Lookups!L44*L40,VLOOKUP($D40&\"_\"&$E40,Lookups!$J$3:$M$83,3,0)*$L40))))","v":""},"","",{"$f":"IF(OR(D40=\"\",E40=\"\", D40=\"LED Refrig Case Lighting\",D40=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D40=\"Hot Holding Cabinets\",E40=\"Half Size\"),Lookups!M24*L40,IF(AND(D40=\"Hot Holding Cabinets\",E40=\"3/4 Size\"),Lookups!M34*L40,IF(AND(D40=\"Hot Holding Cabinets\",E40=\"Full Size\"),Lookups!M44*L40,VLOOKUP($D40&\"_\"&$E40,Lookups!$J$3:$M$83,4,0)*$L40))))","v":""},"",""]
[null,19,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D41=\"\",\"\",VLOOKUP(D41,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D41=\"\",E41=\"\"),\"\",VLOOKUP($D41&\"_\"&$E41,Lookups!$J$3:$M$83,2,0)*$L41)","v":""},{"$f":"IF(OR(D41=\"\",E41=\"\", D41=\"LED Refrig Case Lighting\",D41=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D41=\"Hot Holding Cabinets\",E41=\"Half Size\"),Lookups!L25*L41,IF(AND(D41=\"Hot Holding Cabinets\",E41=\"3/4 Size\"),Lookups!L35*L41,IF(AND(D41=\"Hot Holding Cabinets\",E41=\"Full Size\"),Lookups!L45*L41,VLOOKUP($D41&\"_\"&$E41,Lookups!$J$3:$M$83,3,0)*$L41))))","v":""},"","",{"$f":"IF(OR(D41=\"\",E41=\"\", D41=\"LED Refrig Case Lighting\",D41=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D41=\"Hot Holding Cabinets\",E41=\"Half Size\"),Lookups!M25*L41,IF(AND(D41=\"Hot Holding Cabinets\",E41=\"3/4 Size\"),Lookups!M35*L41,IF(AND(D41=\"Hot Holding Cabinets\",E41=\"Full Size\"),Lookups!M45*L41,VLOOKUP($D41&\"_\"&$E41,Lookups!$J$3:$M$83,4,0)*$L41))))","v":""},"",""]
[null,20,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(D42=\"\",\"\",VLOOKUP(D42,Lookups!$D$3:$E$31,2,0))","v":""},{"$f":"IF(OR(D42=\"\",E42=\"\"),\"\",VLOOKUP($D42&\"_\"&$E42,Lookups!$J$3:$M$83,2,0)*$L42)","v":""},{"$f":"IF(OR(D42=\"\",E42=\"\", D42=\"LED Refrig Case Lighting\",D42=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D42=\"Hot Holding Cabinets\",E42=\"Half Size\"),Lookups!L26*L42,IF(AND(D42=\"Hot Holding Cabinets\",E42=\"3/4 Size\"),Lookups!L36*L42,IF(AND(D42=\"Hot Holding Cabinets\",E42=\"Full Size\"),Lookups!L46*L42,VLOOKUP($D42&\"_\"&$E42,Lookups!$J$3:$M$83,3,0)*$L42))))","v":""},"","",{"$f":"IF(OR(D42=\"\",E42=\"\", D42=\"LED Refrig Case Lighting\",D42=\"LED Refrig Case Lighting Controls\"),\"\",IF(AND(D42=\"Hot Holding Cabinets\",E42=\"Half Size\"),Lookups!M26*L42,IF(AND(D42=\"Hot Holding Cabinets\",E42=\"3/4 Size\"),Lookups!M36*L42,IF(AND(D42=\"Hot Holding Cabinets\",E42=\"Full Size\"),Lookups!M46*L42,VLOOKUP($D42&\"_\"&$E42,Lookups!$J$3:$M$83,4,0)*$L42))))","v":""},"",""]

{"sheet":"Input Key","index":8,"n_rows":22,"n_cols":4,"rows_kept":22,"cut":false,"hidden":true,"merged":[]}
[]
[]
[null,"Building Type",null,"Measure Type"]
[null,"Office",null,"Steam Cookers"]
[null,"Retail",null,"Hot Holding Cabinets"]
[null,"School",null,"Fryers"]
[null,"University",null,"Griddles"]
[null,"Religious Facility",null,"Convection Ovens"]
[null,"Grocery",null,"Combination Ovens"]
[null,"Lodging",null,"Ice Machines Tier 1"]
[null,"Industrial",null,"Ice Machines Tier 2 - Cube"]
[null,"Warehouse",null,"Ice Machines Tier 2 - Flake"]
[null,"Health Facility",null,"Reach-in Refrigerators"]
[null,"Multifamily",null,"Glass Door Reach-in Refrig"]
[null,"Restaurant",null,"Reach-in Freezers"]
[null,"Other",null,"Clothes Washers"]
[null,null,null,"Anti-Sweat Heater Controls"]
[null,null,null,"ECM (Coolers/Freezers)"]
[null,null,null,"Refrigeration Night Covers"]
[null,null,null,"LED Refrig Case Lighting"]
[null,null,null,"LED Refrig Case Lighting Controls"]
[null,null,null,"Vending Machine Controls "]

{"sheet":"Measure Summary","index":9,"n_rows":40,"n_cols":10,"rows_kept":40,"cut":false,"hidden":false,"merged":[[39,7,39,8],[19,5,19,6],[23,5,23,6],[34,5,34,6],[13,7,13,8],[38,5,38,6],[35,5,35,6],[36,5,36,6],[24,5,24,6],[20,5,20,6],[21,5,21,6],[22,5,22,6],[25,5,25,6],[26,5,26,6],[27,5,27,6],[28,5,28,6],[10,7,10,8],[17,3,18,3],[17,4,18,4],[13,3,13,4],[1,1,1,9],[2,1,2,9],[3,1,3,9],[4,1,4,9],[12,3,12,4],[5,1,5,9],[8,1,8,9],[11,7,11,8],[12,7,12,8],[17,1,18,1],[17,2,18,2],[10,3,10,4],[11,3,11,4],[17,5,18,6],[17,9,18,9],[17,7,18,7],[17,8,18,8],[37,5,37,6],[29,5,29,6],[30,5,30,6],[31,5,31,6],[32,5,32,6],[33,5,33,6]]}
[]
[]
[null,"C&I Prescriptive Program"]
[null,"Food Service and High-Efficiency Equipment"]
[null,"Measure Summary"]
[null,{"$f":"\"Version # \"&'Version Tracking'!C4","v":"Version # 14.3"}]
[null,"Copyright © 2023 ICF Resources, LLC, All Rights Reserved. Do not copy, distribute or quote without ICF’s written permission."]
[]
[null,"Required General Project Information"]
[]
[null,null,"Project Name",{"$f":"IF('Equipment Input'!D11=\"\",\"\",'Equipment Input'!D11)","v":""},null,null,"Prepared By",{"$f":"IF('Equipment Input'!G11=\"\",\"\",'Equipment Input'!G11)","v":""}]
[null,null,"Project Address",{"$f":"IF('Equipment Input'!D12=\"\",\"\",'Equipment Input'!D12)","v":""},null,null,"Contact Person",{"$f":"IF('Equipment Input'!G12=\"\",\"\",'Equipment Input'!G12)","v":""}]
[null,null,"City",{"$f":"IF('Equipment Input'!D13=\"\",\"\",'Equipment Input'!D13)","v":""},null,null,"Phone",{"$f":"IF('Equipment Input'!G13=\"\",\"\",'Equipment Input'!G13)","v":""}]
[null,null,"ZIP",{"$f":"IF('Equipment Input'!D14=\"\",\"\",'Equipment Input'!D14)","v":""},null,null,"Email",{"$f":"IF('Equipment Input'!G14=\"\",\"\",'Equipment Input'!G14)","v":""}]
[]
[]
[null,"Food Service & High Efficiency Equipment Information"]
[null,"Measure Type","Type/Size","Make","Model","Incentive/Units",null,"Units","Quantity","Subtotal Incentive"]
[]
[null,{"$f":"IF('Equipment Input'!D23=\"\",\"\",'Equipment Input'!D23)","v":""},{"$f":"IF('Equipment Input'!E23=\"\",\"\",'Equipment Input'!E23)","v":""},{"$f":"IF('Equipment Input'!F23=\"\",\"\",'Equipment Input'!F23)","v":""},{"$f":"IF('Equipment Input'!G23=\"\",\"\",'Equipment Input'!G23)","v":""},{"$f":"IF(OR(B20=\"\",C20=\"\"),\"\",VLOOKUP(B20&\"_\"&C20,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M23=\"\",\"\",'Equipment Input'!M23)","v":""},{"$f":"IF('Equipment Input'!M23=\"\",\"\",'Equipment Input'!M23)","v":""},{"$f":"IF('Equipment Input'!L23=\"\",\"\",'Equipment Input'!L23)","v":""},{"$f":"IF('Equipment Input'!N23=\"\",\"\",'Equipment Input'!N23)","v":""}]
[null,{"$f":"IF('Equipment Input'!D24=\"\",\"\",'Equipment Input'!D24)","v":""},{"$f":"IF('Equipment Input'!E24=\"\",\"\",'Equipment Input'!E24)","v":""},{"$f":"IF('Equipment Input'!F24=\"\",\"\",'Equipment Input'!F24)","v":""},{"$f":"IF('Equipment Input'!G24=\"\",\"\",'Equipment Input'!G24)","v":""},{"$f":"IF(OR(B21=\"\",C21=\"\"),\"\",VLOOKUP(B21&\"_\"&C21,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M24=\"\",\"\",'Equipment Input'!M24)","v":""},{"$f":"IF('Equipment Input'!M24=\"\",\"\",'Equipment Input'!M24)","v":""},{"$f":"IF('Equipment Input'!L24=\"\",\"\",'Equipment Input'!L24)","v":""},{"$f":"IF('Equipment Input'!N24=\"\",\"\",'Equipment Input'!N24)","v":""}]
[null,{"$f":"IF('Equipment Input'!D25=\"\",\"\",'Equipment Input'!D25)","v":""},{"$f":"IF('Equipment Input'!E25=\"\",\"\",'Equipment Input'!E25)","v":""},{"$f":"IF('Equipment Input'!F25=\"\",\"\",'Equipment Input'!F25)","v":""},{"$f":"IF('Equipment Input'!G25=\"\",\"\",'Equipment Input'!G25)","v":""},{"$f":"IF(OR(B22=\"\",C22=\"\"),\"\",VLOOKUP(B22&\"_\"&C22,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M25=\"\",\"\",'Equipment Input'!M25)","v":""},{"$f":"IF('Equipment Input'!M25=\"\",\"\",'Equipment Input'!M25)","v":""},{"$f":"IF('Equipment Input'!L25=\"\",\"\",'Equipment Input'!L25)","v":""},{"$f":"IF('Equipment Input'!N25=\"\",\"\",'Equipment Input'!N25)","v":""}]
[null,{"$f":"IF('Equipment Input'!D26=\"\",\"\",'Equipment Input'!D26)","v":""},{"$f":"IF('Equipment Input'!E26=\"\",\"\",'Equipment Input'!E26)","v":""},{"$f":"IF('Equipment Input'!F26=\"\",\"\",'Equipment Input'!F26)","v":""},{"$f":"IF('Equipment Input'!G26=\"\",\"\",'Equipment Input'!G26)","v":""},{"$f":"IF(OR(B23=\"\",C23=\"\"),\"\",VLOOKUP(B23&\"_\"&C23,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M26=\"\",\"\",'Equipment Input'!M26)","v":""},{"$f":"IF('Equipment Input'!M26=\"\",\"\",'Equipment Input'!M26)","v":""},{"$f":"IF('Equipment Input'!L26=\"\",\"\",'Equipment Input'!L26)","v":""},{"$f":"IF('Equipment Input'!N26=\"\",\"\",'Equipment Input'!N26)","v":""}]
[null,{"$f":"IF('Equipment Input'!D27=\"\",\"\",'Equipment Input'!D27)","v":""},{"$f":"IF('Equipment Input'!E27=\"\",\"\",'Equipment Input'!E27)","v":""},{"$f":"IF('Equipment Input'!F27=\"\",\"\",'Equipment Input'!F27)","v":""},{"$f":"IF('Equipment Input'!G27=\"\",\"\",'Equipment Input'!G27)","v":""},{"$f":"IF(OR(B24=\"\",C24=\"\"),\"\",VLOOKUP(B24&\"_\"&C24,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M27=\"\",\"\",'Equipment Input'!M27)","v":""},{"$f":"IF('Equipment Input'!M27=\"\",\"\",'Equipment Input'!M27)","v":""},{"$f":"IF('Equipment Input'!L27=\"\",\"\",'Equipment Input'!L27)","v":""},{"$f":"IF('Equipment Input'!N27=\"\",\"\",'Equipment Input'!N27)","v":""}]
[null,{"$f":"IF('Equipment Input'!D28=\"\",\"\",'Equipment Input'!D28)","v":""},{"$f":"IF('Equipment Input'!E28=\"\",\"\",'Equipment Input'!E28)","v":""},{"$f":"IF('Equipment Input'!F28=\"\",\"\",'Equipment Input'!F28)","v":""},{"$f":"IF('Equipment Input'!G28=\"\",\"\",'Equipment Input'!G28)","v":""},{"$f":"IF(OR(B25=\"\",C25=\"\"),\"\",VLOOKUP(B25&\"_\"&C25,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M28=\"\",\"\",'Equipment Input'!M28)","v":""},{"$f":"IF('Equipment Input'!M28=\"\",\"\",'Equipment Input'!M28)","v":""},{"$f":"IF('Equipment Input'!L28=\"\",\"\",'Equipment Input'!L28)","v":""},{"$f":"IF('Equipment Input'!N28=\"\",\"\",'Equipment Input'!N28)","v":""}]
[null,{"$f":"IF('Equipment Input'!D29=\"\",\"\",'Equipment Input'!D29)","v":""},{"$f":"IF('Equipment Input'!E29=\"\",\"\",'Equipment Input'!E29)","v":""},{"$f":"IF('Equipment Input'!F29=\"\",\"\",'Equipment Input'!F29)","v":""},{"$f":"IF('Equipment Input'!G29=\"\",\"\",'Equipment Input'!G29)","v":""},{"$f":"IF(OR(B26=\"\",C26=\"\"),\"\",VLOOKUP(B26&\"_\"&C26,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M29=\"\",\"\",'Equipment Input'!M29)","v":""},{"$f":"IF('Equipment Input'!M29=\"\",\"\",'Equipment Input'!M29)","v":""},{"$f":"IF('Equipment Input'!L29=\"\",\"\",'Equipment Input'!L29)","v":""},{"$f":"IF('Equipment Input'!N29=\"\",\"\",'Equipment Input'!N29)","v":""}]
[null,{"$f":"IF('Equipment Input'!D30=\"\",\"\",'Equipment Input'!D30)","v":""},{"$f":"IF('Equipment Input'!E30=\"\",\"\",'Equipment Input'!E30)","v":""},{"$f":"IF('Equipment Input'!F30=\"\",\"\",'Equipment Input'!F30)","v":""},{"$f":"IF('Equipment Input'!G30=\"\",\"\",'Equipment Input'!G30)","v":""},{"$f":"IF(OR(B27=\"\",C27=\"\"),\"\",VLOOKUP(B27&\"_\"&C27,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M30=\"\",\"\",'Equipment Input'!M30)","v":""},{"$f":"IF('Equipment Input'!M30=\"\",\"\",'Equipment Input'!M30)","v":""},{"$f":"IF('Equipment Input'!L30=\"\",\"\",'Equipment Input'!L30)","v":""},{"$f":"IF('Equipment Input'!N30=\"\",\"\",'Equipment Input'!N30)","v":""}]
[null,{"$f":"IF('Equipment Input'!D31=\"\",\"\",'Equipment Input'!D31)","v":""},{"$f":"IF('Equipment Input'!E31=\"\",\"\",'Equipment Input'!E31)","v":""},{"$f":"IF('Equipment Input'!F31=\"\",\"\",'Equipment Input'!F31)","v":""},{"$f":"IF('Equipment Input'!G31=\"\",\"\",'Equipment Input'!G31)","v":""},{"$f":"IF(OR(B28=\"\",C28=\"\"),\"\",VLOOKUP(B28&\"_\"&C28,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M31=\"\",\"\",'Equipment Input'!M31)","v":""},{"$f":"IF('Equipment Input'!M31=\"\",\"\",'Equipment Input'!M31)","v":""},{"$f":"IF('Equipment Input'!L31=\"\",\"\",'Equipment Input'!L31)","v":""},{"$f":"IF('Equipment Input'!N31=\"\",\"\",'Equipment Input'!N31)","v":""}]
[null,{"$f":"IF('Equipment Input'!D32=\"\",\"\",'Equipment Input'!D32)","v":""},{"$f":"IF('Equipment Input'!E32=\"\",\"\",'Equipment Input'!E32)","v":""},{"$f":"IF('Equipment Input'!F32=\"\",\"\",'Equipment Input'!F32)","v":""},{"$f":"IF('Equipment Input'!G32=\"\",\"\",'Equipment Input'!G32)","v":""},{"$f":"IF(OR(B29=\"\",C29=\"\"),\"\",VLOOKUP(B29&\"_\"&C29,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M32=\"\",\"\",'Equipment Input'!M32)","v":""},{"$f":"IF('Equipment Input'!M32=\"\",\"\",'Equipment Input'!M32)","v":""},{"$f":"IF('Equipment Input'!L32=\"\",\"\",'Equipment Input'!L32)","v":""},{"$f":"IF('Equipment Input'!N32=\"\",\"\",'Equipment Input'!N32)","v":""}]
[null,{"$f":"IF('Equipment Input'!D33=\"\",\"\",'Equipment Input'!D33)","v":""},{"$f":"IF('Equipment Input'!E33=\"\",\"\",'Equipment Input'!E33)","v":""},{"$f":"IF('Equipment Input'!F33=\"\",\"\",'Equipment Input'!F33)","v":""},{"$f":"IF('Equipment Input'!G33=\"\",\"\",'Equipment Input'!G33)","v":""},{"$f":"IF(OR(B30=\"\",C30=\"\"),\"\",VLOOKUP(B30&\"_\"&C30,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M33=\"\",\"\",'Equipment Input'!M33)","v":""},{"$f":"IF('Equipment Input'!M33=\"\",\"\",'Equipment Input'!M33)","v":""},{"$f":"IF('Equipment Input'!L33=\"\",\"\",'Equipment Input'!L33)","v":""},{"$f":"IF('Equipment Input'!N33=\"\",\"\",'Equipment Input'!N33)","v":""}]
[null,{"$f":"IF('Equipment Input'!D34=\"\",\"\",'Equipment Input'!D34)","v":""},{"$f":"IF('Equipment Input'!E34=\"\",\"\",'Equipment Input'!E34)","v":""},{"$f":"IF('Equipment Input'!F34=\"\",\"\",'Equipment Input'!F34)","v":""},{"$f":"IF('Equipment Input'!G34=\"\",\"\",'Equipment Input'!G34)","v":""},{"$f":"IF(OR(B31=\"\",C31=\"\"),\"\",VLOOKUP(B31&\"_\"&C31,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M34=\"\",\"\",'Equipment Input'!M34)","v":""},{"$f":"IF('Equipment Input'!M34=\"\",\"\",'Equipment Input'!M34)","v":""},{"$f":"IF('Equipment Input'!L34=\"\",\"\",'Equipment Input'!L34)","v":""},{"$f":"IF('Equipment Input'!N34=\"\",\"\",'Equipment Input'!N34)","v":""}]
[null,{"$f":"IF('Equipment Input'!D35=\"\",\"\",'Equipment Input'!D35)","v":""},{"$f":"IF('Equipment Input'!E35=\"\",\"\",'Equipment Input'!E35)","v":""},{"$f":"IF('Equipment Input'!F35=\"\",\"\",'Equipment Input'!F35)","v":""},{"$f":"IF('Equipment Input'!G35=\"\",\"\",'Equipment Input'!G35)","v":""},{"$f":"IF(OR(B32=\"\",C32=\"\"),\"\",VLOOKUP(B32&\"_\"&C32,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M35=\"\",\"\",'Equipment Input'!M35)","v":""},{"$f":"IF('Equipment Input'!M35=\"\",\"\",'Equipment Input'!M35)","v":""},{"$f":"IF('Equipment Input'!L35=\"\",\"\",'Equipment Input'!L35)","v":""},{"$f":"IF('Equipment Input'!N35=\"\",\"\",'Equipment Input'!N35)","v":""}]
[null,{"$f":"IF('Equipment Input'!D36=\"\",\"\",'Equipment Input'!D36)","v":""},{"$f":"IF('Equipment Input'!E36=\"\",\"\",'Equipment Input'!E36)","v":""},{"$f":"IF('Equipment Input'!F36=\"\",\"\",'Equipment Input'!F36)","v":""},{"$f":"IF('Equipment Input'!G36=\"\",\"\",'Equipment Input'!G36)","v":""},{"$f":"IF(OR(B33=\"\",C33=\"\"),\"\",VLOOKUP(B33&\"_\"&C33,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M36=\"\",\"\",'Equipment Input'!M36)","v":""},{"$f":"IF('Equipment Input'!M36=\"\",\"\",'Equipment Input'!M36)","v":""},{"$f":"IF('Equipment Input'!L36=\"\",\"\",'Equipment Input'!L36)","v":""},{"$f":"IF('Equipment Input'!N36=\"\",\"\",'Equipment Input'!N36)","v":""}]
[null,{"$f":"IF('Equipment Input'!D37=\"\",\"\",'Equipment Input'!D37)","v":""},{"$f":"IF('Equipment Input'!E37=\"\",\"\",'Equipment Input'!E37)","v":""},{"$f":"IF('Equipment Input'!F37=\"\",\"\",'Equipment Input'!F37)","v":""},{"$f":"IF('Equipment Input'!G37=\"\",\"\",'Equipment Input'!G37)","v":""},{"$f":"IF(OR(B34=\"\",C34=\"\"),\"\",VLOOKUP(B34&\"_\"&C34,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M37=\"\",\"\",'Equipment Input'!M37)","v":""},{"$f":"IF('Equipment Input'!M37=\"\",\"\",'Equipment Input'!M37)","v":""},{"$f":"IF('Equipment Input'!L37=\"\",\"\",'Equipment Input'!L37)","v":""},{"$f":"IF('Equipment Input'!N37=\"\",\"\",'Equipment Input'!N37)","v":""}]
[null,{"$f":"IF('Equipment Input'!D38=\"\",\"\",'Equipment Input'!D38)","v":""},{"$f":"IF('Equipment Input'!E38=\"\",\"\",'Equipment Input'!E38)","v":""},{"$f":"IF('Equipment Input'!F38=\"\",\"\",'Equipment Input'!F38)","v":""},{"$f":"IF('Equipment Input'!G38=\"\",\"\",'Equipment Input'!G38)","v":""},{"$f":"IF(OR(B35=\"\",C35=\"\"),\"\",VLOOKUP(B35&\"_\"&C35,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M38=\"\",\"\",'Equipment Input'!M38)","v":""},{"$f":"IF('Equipment Input'!M38=\"\",\"\",'Equipment Input'!M38)","v":""},{"$f":"IF('Equipment Input'!L38=\"\",\"\",'Equipment Input'!L38)","v":""},{"$f":"IF('Equipment Input'!N38=\"\",\"\",'Equipment Input'!N38)","v":""}]
[null,{"$f":"IF('Equipment Input'!D39=\"\",\"\",'Equipment Input'!D39)","v":""},{"$f":"IF('Equipment Input'!E39=\"\",\"\",'Equipment Input'!E39)","v":""},{"$f":"IF('Equipment Input'!F39=\"\",\"\",'Equipment Input'!F39)","v":""},{"$f":"IF('Equipment Input'!G39=\"\",\"\",'Equipment Input'!G39)","v":""},{"$f":"IF(OR(B36=\"\",C36=\"\"),\"\",VLOOKUP(B36&\"_\"&C36,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M39=\"\",\"\",'Equipment Input'!M39)","v":""},{"$f":"IF('Equipment Input'!M39=\"\",\"\",'Equipment Input'!M39)","v":""},{"$f":"IF('Equipment Input'!L39=\"\",\"\",'Equipment Input'!L39)","v":""},{"$f":"IF('Equipment Input'!N39=\"\",\"\",'Equipment Input'!N39)","v":""}]
[null,{"$f":"IF('Equipment Input'!D40=\"\",\"\",'Equipment Input'!D40)","v":""},{"$f":"IF('Equipment Input'!E40=\"\",\"\",'Equipment Input'!E40)","v":""},{"$f":"IF('Equipment Input'!F40=\"\",\"\",'Equipment Input'!F40)","v":""},{"$f":"IF('Equipment Input'!G40=\"\",\"\",'Equipment Input'!G40)","v":""},{"$f":"IF(OR(B37=\"\",C37=\"\"),\"\",VLOOKUP(B37&\"_\"&C37,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M40=\"\",\"\",'Equipment Input'!M40)","v":""},{"$f":"IF('Equipment Input'!M40=\"\",\"\",'Equipment Input'!M40)","v":""},{"$f":"IF('Equipment Input'!L40=\"\",\"\",'Equipment Input'!L40)","v":""},{"$f":"IF('Equipment Input'!N40=\"\",\"\",'Equipment Input'!N40)","v":""}]
[null,{"$f":"IF('Equipment Input'!D41=\"\",\"\",'Equipment Input'!D41)","v":""},{"$f":"IF('Equipment Input'!E41=\"\",\"\",'Equipment Input'!E41)","v":""},{"$f":"IF('Equipment Input'!F41=\"\",\"\",'Equipment Input'!F41)","v":""},{"$f":"IF('Equipment Input'!G41=\"\",\"\",'Equipment Input'!G41)","v":""},{"$f":"IF(OR(B38=\"\",C38=\"\"),\"\",VLOOKUP(B38&\"_\"&C38,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M41=\"\",\"\",'Equipment Input'!M41)","v":""},{"$f":"IF('Equipment Input'!M41=\"\",\"\",'Equipment Input'!M41)","v":""},{"$f":"IF('Equipment Input'!L41=\"\",\"\",'Equipment Input'!L41)","v":""},{"$f":"IF('Equipment Input'!N41=\"\",\"\",'Equipment Input'!N41)","v":""}]
[null,{"$f":"IF('Equipment Input'!D42=\"\",\"\",'Equipment Input'!D42)","v":""},{"$f":"IF('Equipment Input'!E42=\"\",\"\",'Equipment Input'!E42)","v":""},{"$f":"IF('Equipment Input'!F42=\"\",\"\",'Equipment Input'!F42)","v":""},{"$f":"IF('Equipment Input'!G42=\"\",\"\",'Equipment Input'!G42)","v":""},{"$f":"IF(OR(B39=\"\",C39=\"\"),\"\",VLOOKUP(B39&\"_\"&C39,Lookups!$J$3:$K$83,2,0))","v":""},{"$f":"IF('Equipment Input'!M42=\"\",\"\",'Equipment Input'!M42)","v":""},{"$f":"IF('Equipment Input'!M42=\"\",\"\",'Equipment Input'!M42)","v":""},{"$f":"IF('Equipment Input'!L42=\"\",\"\",'Equipment Input'!L42)","v":""},{"$f":"IF('Equipment Input'!N42=\"\",\"\",'Equipment Input'!N42)","v":""}]
[null,null,null,null,null,null,null,"Total Pre-approved Incentive",null,{"$f":"SUM(J20:J39)","v":0}]

{"sheet":"Validation","index":10,"n_rows":56,"n_cols":33,"rows_kept":56,"cut":false,"hidden":true,"merged":[]}
[null,null,null,null,null,null,{"$f":"COUNTA(G3:G19)","v":4},{"$f":"COUNTA(H3:H19)","v":3},1,1,1,1,3,3,4,4,4,4,2,2,{"$f":"COUNTA(U3:U17)","v":8},2,2,2,2,1]
[null,"Building Type",null,"Measure Type","Useful Life",null,"Steam Cookers","Hot Holding Cabinets","Fryers","Griddles","Convection Ovens","Combination Ovens","Ice Machines Batch","Ice Machines Continuous","Reach-in Refrigerators","Glass Door Reach-in Refrig","Reach-in Freezers","Glass Door Reach-in Freezers","Clothes Washers","Anti-Sweat Heater Controls","ECM (Coolers/Freezers)","Refrigeration Night Covers","LED Refrig Case Lighting","LED Refrig Case Lighting Controls","Vending Machine Controls","Personal Recept Occ Sensors",null,null,"Measure Type","Size","MeasureType+Size","Measure Code","Useful Life"]
[null,"Office",null,"Steam Cookers",12,null,"3 Pan","Half Size","Large Vat","All","All","All","Ice Making Head","Ice Making Head","< 15 cubic feet","< 15 cubic feet","< 15 cubic feet","< 15 cubic feet","Electric water heater","Cooler Doors","Reach-in Cooler","Freezers","Coolers","Coolers","Refrigerated","Power Strip with Occupancy Sensor",null,null,"Steam Cookers","3 Pan",{"$f":"CONCATENATE(AC3, \" \",AD3)","v":"Steam Cookers 3 Pan"},"SC3",{"$f":"VLOOKUP(AC3,$D$3:$E$22,2,FALSE)","v":12}]
[null,"Retail",null,"Hot Holding Cabinets",12,null,"4 Pan","3/4 Size",null,null,null,null,"Split System","Split System","15 - 30 cubic feet","15 - 30 cubic feet","15 - 30 cubic feet","15 - 30 cubic feet","Non-electric water heater","Freezer Doors","Reach-in Freezer","Coolers","Freezers","Freezers","Non-Refrigerated",null,null,null,"Steam Cookers","4 Pan","Steam Cookers 4 Pan","SC4",12]
[null,"School",null,"Fryers",12,null,"5 Pan","Full Size",null,null,null,null,"Self-Contained","Self-Contained","31 - 50 cubic feet","31 - 50 cubic feet","31 - 50 cubic feet","31 - 50 cubic feet",null,null,"Display Cooler",null,null,null,null,null,null,null,"Steam Cookers","5 Pan","Steam Cookers 5 Pan","SC5",12]
[null,"University",null,"Griddles",12,null,"6 Pan",null,null,null,null,null,null,null,"> 50 cubic feet","> 50 cubic feet","> 50 cubic feet","> 50 cubic feet",null,null,"Display Freezer",null,null,null,null,null,null,null,"Steam Cookers","6 Pan","Steam Cookers 6 Pan","SC6",12]
[null,"Religious Facility",null,"Convection Ovens",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Walk-in Cooler replacing PSC",null,null,null,null,null,null,null,"Hot Holding Cabinets","Half Size","Hot Holding Cabinets Half Size","HC1",12]
[null,"Grocery",null,"Combination Ovens",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Walk-in Freezer replacing PSC",null,null,null,null,null,null,null,"Hot Holding Cabinets","3/4 Size","Hot Holding Cabinets 3/4 Size","HC2",12]
[null,"Lodging",null,"Ice Machines Batch",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Walk-in Cooler replacing Shaded Poll",null,null,null,null,null,null,null,"Hot Holding Cabinets","Full Size","Hot Holding Cabinets Full Size","HCF",12]
[null,"Industrial",null,"Ice Machines Continuous",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Walk-in Freezer replacing Shaded Poll",null,null,null,null,null,null,null,"Fryers","Large Vat","Fryers Large Vat","FLV",12]
[null,"Warehouse",null,"Reach-in Refrigerators",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Griddles","All","Griddles All","GRD",12]
[null,"Health Facility",null,"Glass Door Reach-in Refrig",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Convection Ovens","All","Convection Ovens All","CVO",12]
[null,"Multifamily",null,"Reach-in Freezers",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Combination Ovens","All","Combination Ovens All","CMBO",12]
[null,"Restaurant",null,"Glass Door Reach-in Freezers",12,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Clothes Washers","Electric water heater","Clothes Washers Electric water heater","CLW",10]
[null,"Other",null,"Clothes Washers",11,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Clothes Washers","Non-electric water heater","Clothes Washers Non-electric water heater","CLW",10]
[null,null,null,"Anti-Sweat Heater Controls",16,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ice Machines Batch","Ice Making Head","Ice Machines Batch Ice Making Head","IC26",{"$f":"VLOOKUP(AC16,$D$3:$E$22,2,FALSE)","v":12}]
[null,null,null,"ECM (Coolers/Freezers)",10,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ice Machines Batch","Split System","Ice Machines Batch Split System","IC27",12]
[null,null,null,"Refrigeration Night Covers",5,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ice Machines Batch","Self-Contained","Ice Machines Batch Self-Contained","IC28",12]
[null,null,null,"LED Refrig Case Lighting",10,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ice Machines Continuous","Ice Making Head","Ice Machines Continuous Ice Making Head","IC29",12]
[null,null,null,"LED Refrig Case Lighting Controls",10,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ice Machines Continuous","Split System",{"$f":"CONCATENATE(AC20, \" \",AD20)","v":"Ice Machines Continuous Split System"},"IC30",12]
[null,null,null,"Vending Machine Controls",10,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Ice Machines Continuous","Self-Contained","Ice Machines Continuous Self-Contained","IC31",12]
[null,null,null,"Personal Recept Occ Sensors",10,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Refrigerators","< 15 cubic feet","Reach-in Refrigerators < 15 cubic feet","RR1",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Refrigerators","15 - 30 cubic feet","Reach-in Refrigerators 15 - 30 cubic feet","RR2",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Refrigerators","31 - 50 cubic feet","Reach-in Refrigerators 31 - 50 cubic feet","RR3",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Refrigerators","> 50 cubic feet","Reach-in Refrigerators > 50 cubic feet","RR4",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Refrig","< 15 cubic feet","Glass Door Reach-in Refrig < 15 cubic feet","GDR1",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Refrig","15 - 30 cubic feet","Glass Door Reach-in Refrig 15 - 30 cubic feet","GDR2",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Refrig","31 - 50 cubic feet","Glass Door Reach-in Refrig 31 - 50 cubic feet","GDR3",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Refrig","> 50 cubic feet","Glass Door Reach-in Refrig > 50 cubic feet","GDR4",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Freezers","< 15 cubic feet","Reach-in Freezers < 15 cubic feet","RF1",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Freezers","15 - 30 cubic feet","Reach-in Freezers 15 - 30 cubic feet","RF2",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Freezers","31 - 50 cubic feet","Reach-in Freezers 31 - 50 cubic feet","RF3",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reach-in Freezers","> 50 cubic feet","Reach-in Freezers > 50 cubic feet","RF4",{"$f":"VLOOKUP(AC33,$D$3:$E$22,2,FALSE)","v":12}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Freezers","< 15 cubic feet",{"$f":"CONCATENATE(AC34, \" \",AD34)","v":"Glass Door Reach-in Freezers < 15 cubic feet"},"GDF1",{"$f":"VLOOKUP(AC34,$D$3:$E$22,2,FALSE)","v":12}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Freezers","15 - 30 cubic feet","Glass Door Reach-in Freezers 15 - 30 cubic feet","GDF2",{"$f":"VLOOKUP(AC35,$D$3:$E$22,2,FALSE)","v":12}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Freezers","31 - 50 cubic feet","Glass Door Reach-in Freezers 31 - 50 cubic feet","GDF3",{"$f":"VLOOKUP(AC36,$D$3:$E$22,2,FALSE)","v":12}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Glass Door Reach-in Freezers","> 50 cubic feet","Glass Door Reach-in Freezers > 50 cubic feet","GDF4",12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Reach-in Cooler","ECM (Coolers/Freezers) Reach-in Cooler","ECMR1",{"$f":"VLOOKUP(AC38,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Reach-in Freezer","ECM (Coolers/Freezers) Reach-in Freezer","ECMR2",{"$f":"VLOOKUP(AC39,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Display Cooler","ECM (Coolers/Freezers) Display Cooler","ECMD1",{"$f":"VLOOKUP(AC40,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Display Freezer","ECM (Coolers/Freezers) Display Freezer","ECMD2",{"$f":"VLOOKUP(AC41,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Cooler replacing PSC","ECM (Coolers/Freezers) Walk-in Cooler replacing PSC","ECMW1",{"$f":"VLOOKUP(AC42,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Freezer replacing PSC","ECM (Coolers/Freezers) Walk-in Freezer replacing PSC","ECMW2",10]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Cooler replacing Shaded Poll","ECM (Coolers/Freezers) Walk-in Cooler replacing Shaded Poll","ECMW1",10]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Freezer replacing Shaded Poll","ECM (Coolers/Freezers) Walk-in Freezer replacing Shaded Poll","ECMW2",10]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Refrigeration Night Covers","Freezers","Refrigeration Night Covers Freezers","RNC1",{"$f":"VLOOKUP(AC46,$D$3:$E$22,2,FALSE)","v":5}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Refrigeration Night Covers","Coolers","Refrigeration Night Covers Coolers","RNC2",{"$f":"VLOOKUP(AC47,$D$3:$E$22,2,FALSE)","v":5}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"LED Refrig Case Lighting","Freezers","LED Refrig Case Lighting Freezers","LEDRF",10]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"LED Refrig Case Lighting","Coolers","LED Refrig Case Lighting Coolers","LEDRL",{"$f":"VLOOKUP(AC49,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"LED Refrig Case Lighting Controls","Freezers","LED Refrig Case Lighting Controls Freezers","LEDRC",{"$f":"VLOOKUP(AC50,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"LED Refrig Case Lighting Controls","Coolers","LED Refrig Case Lighting Controls Coolers","LEDRC",{"$f":"VLOOKUP(AC51,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Anti-Sweat Heater Controls","Cooler Doors","Anti-Sweat Heater Controls Cooler Doors","ASCD",10]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Anti-Sweat Heater Controls","Freezer Doors","Anti-Sweat Heater Controls Freezer Doors","ASFD",10]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Vending Machine Controls","Refrigerated","Vending Machine Controls Refrigerated","VMC1",{"$f":"VLOOKUP(AC54,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Vending Machine Controls","Non-Refrigerated","Vending Machine Controls Non-Refrigerated","VMC2",{"$f":"VLOOKUP(AC55,$D$3:$E$22,2,FALSE)","v":10}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Personal Recept Occ Sensors","Power Strip with Occupancy Sensor","Personal Recept Occ Sensors Power Strip with Occupancy Sensor","PROS",{"$f":"VLOOKUP(AC56,$D$3:$E$22,2,FALSE)","v":10}]

{"sheet":"Lookups","index":11,"n_rows":83,"n_cols":21,"rows_kept":83,"cut":false,"hidden":true,"merged":[]}
[]
[null,null,null,"Units of Quantity",null,null,"Measure Type","Type/Size","Incentive","Concatanation","Incentive","kWh Savings","kW Savings","Hot holderVol. ","Source"]
[null,null,null,"Steam Cookers","Units",null,"Steam Cookers","3 Pan",800,{"$f":"G3&\"_\"&H3","v":"Steam Cookers_3 Pan"},{"$f":"I3","v":800},11188,2.5499999999999998,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"95 Proposed","Wattage ","95 Existing","Wattage"]
[null,null,null,"Hot Holding Cabinets","Units",null,"Steam Cookers","4 pan",800,{"$f":"G4&\"_\"&H4","v":"Steam Cookers_4 pan"},{"$f":"I4","v":800},12459,2.85,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED028",28,"1F59SSE",60]
[null,null,null,"Fryers","Vats",null,"Steam Cookers","5 Pan",1200,"Steam Cookers_5 Pan",1200,13831,3.16,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED029",29,"1F80SSE",85]
[null,null,null,"Griddles","Units",null,"Steam Cookers","6 Pan",1200,"Steam Cookers_6 Pan",1200,15170,3.46,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED030",30,"1F96SSE",83]
[null,null,null,"Convection Ovens","Ovens",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"Half Size\"),((40*N7-(21.5*N7))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"Half Size\"),L7/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"Half Size\"),'Equipment Input'!H23,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED031",31]
[null,null,null,"Combination Ovens","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"Half Size\"),((40*N8-(21.5*N8))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"Half Size\"),L8/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"Half Size\"),'Equipment Input'!H24,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED032",32]
[null,null,null,"Ice Machines Batch","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"Half Size\"),((40*N9-(21.5*N9))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"Half Size\"),L9/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"Half Size\"),'Equipment Input'!H25,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED033",33]
[null,null,null,"Ice Machines Continuous","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"Half Size\"),((40*N10-(21.5*N10))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"Half Size\"),L10/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"Half Size\"),'Equipment Input'!H26,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED034",34]
[null,null,null,"Reach-in Refrigerators","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"Half Size\"),((40*N11-(21.5*N11))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"Half Size\"),L11/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"Half Size\"),'Equipment Input'!H27,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED035",35]
[null,null,null,"Glass Door Reach-in Refrig","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"Half Size\"),((40*N12-(21.5*N12))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"Half Size\"),L12/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"Half Size\"),'Equipment Input'!H35,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED036",36]
[null,null,null,"Reach-in Freezers","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"Half Size\"),((40*N13-(21.5*N13))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"Half Size\"),L13/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"Half Size\"),'Equipment Input'!H39,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED037",37]
[null,null,null,"Glass Door Reach-in Freezers","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"Half Size\"),((40*N14-(21.5*N14))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"Half Size\"),L14/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"Half Size\"),'Equipment Input'!H40,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED038",38]
[null,null,null,"Clothes Washers","Units",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"Half Size\"),((40*N15-(21.5*N15))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"Half Size\"),L15/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"Half Size\"),'Equipment Input'!H41,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED039",39]
[null,null,null,"Anti-Sweat Heater Controls","Doors",null,"Hot Holding Cabinets","Half Size",300,"Hot Holding Cabinets_Half Size",300,{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"Half Size\"),((40*N16-(21.5*N16))*15*365/1000),\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"Half Size\"),L16/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"Half Size\"),'Equipment Input'!H42,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED040",40]
[null,null,null,"ECM (Coolers/Freezers)","Units",null,"Hot Holding Cabinets","3/4 Size",400,{"$f":"G17&\"_\"&H17","v":"Hot Holding Cabinets_3/4 Size"},{"$f":"I17","v":400},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"3/4 Size\"),((40*N17)-(2*N17+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"3/4 Size\"),L17/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"3/4 Size\"),'Equipment Input'!H23,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) ",null,null,"1LED041",41]
[null,null,null,"Refrigeration Night Covers","Linear Feet",null,"Hot Holding Cabinets","3/4 Size",400,{"$f":"G18&\"_\"&H18","v":"Hot Holding Cabinets_3/4 Size"},{"$f":"I18","v":400},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"3/4 Size\"),((40*N18)-(2*N18+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"3/4 Size\"),L18/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"3/4 Size\"),'Equipment Input'!H24,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,"LED Refrig Case Lighting","Doors",null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"3/4 Size\"),((40*N19)-(2*N19+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"3/4 Size\"),L19/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"3/4 Size\"),'Equipment Input'!H25,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,"LED Refrig Case Lighting Controls","Doors",null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"3/4 Size\"),((40*N20)-(2*N20+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"3/4 Size\"),L20/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"3/4 Size\"),'Equipment Input'!H26,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"3/4 Size\"),((40*N21)-(2*N21+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"3/4 Size\"),L21/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"3/4 Size\"),'Equipment Input'!H27,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"3/4 Size\"),((40*N22)-(2*N22+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"3/4 Size\"),L22/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"3/4 Size\"),'Equipment Input'!H35,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"3/4 Size\"),((40*N23)-(2*N23+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"3/4 Size\"),L23/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"3/4 Size\"),'Equipment Input'!H39,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"3/4 Size\"),((40*N24)-(2*N24+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"3/4 Size\"),L24/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"3/4 Size\"),'Equipment Input'!H40,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"3/4 Size\"),((40*N25)-(2*N25+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"3/4 Size\"),L25/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"3/4 Size\"),'Equipment Input'!H41,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","3/4 Size",400,"Hot Holding Cabinets_3/4 Size",400,{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"3/4 Size\"),((40*N26)-(2*N26+254))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"3/4 Size\"),L26/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"3/4 Size\"),'Equipment Input'!H42,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,{"$f":"G27&\"_\"&H27","v":"Hot Holding Cabinets_Full Size"},{"$f":"I27","v":500},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"Full Size\"),((40*N27)-(3.8*N27+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"Full Size\"),L27/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D23=\"Hot Holding Cabinets\",'Equipment Input'!E23=\"Full Size\"),'Equipment Input'!H23,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,{"$f":"G28&\"_\"&H28","v":"Hot Holding Cabinets_Full Size"},{"$f":"I28","v":500},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"Full Size\"),((40*N28)-(3.8*N28+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"Full Size\"),L28/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D24=\"Hot Holding Cabinets\",'Equipment Input'!E24=\"Full Size\"),'Equipment Input'!H24,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"Full Size\"),((40*N29)-(3.8*N29+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"Full Size\"),L29/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D25=\"Hot Holding Cabinets\",'Equipment Input'!E25=\"Full Size\"),'Equipment Input'!H25,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,"Vending Machine Controls","Units",null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"Full Size\"),((40*N30)-(3.8*N30+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"Full Size\"),L30/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D26=\"Hot Holding Cabinets\",'Equipment Input'!E26=\"Full Size\"),'Equipment Input'!H26,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,"Personal Recept Occ Sensors","Controls",null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"Full Size\"),((40*N31)-(3.8*N31+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"Full Size\"),L31/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D27=\"Hot Holding Cabinets\",'Equipment Input'!E27=\"Full Size\"),'Equipment Input'!H27,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"Full Size\"),((40*N32)-(3.8*N32+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"Full Size\"),L32/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D35=\"Hot Holding Cabinets\",'Equipment Input'!E35=\"Full Size\"),'Equipment Input'!H35,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"Full Size\"),((40*N33)-(3.8*N33+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"Full Size\"),L33/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D39=\"Hot Holding Cabinets\",'Equipment Input'!E39=\"Full Size\"),'Equipment Input'!H39,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"Full Size\"),((40*N34)-(3.8*N34+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"Full Size\"),L34/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D40=\"Hot Holding Cabinets\",'Equipment Input'!E40=\"Full Size\"),'Equipment Input'!H40,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"Full Size\"),((40*N35)-(3.8*N35+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"Full Size\"),L35/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D41=\"Hot Holding Cabinets\",'Equipment Input'!E41=\"Full Size\"),'Equipment Input'!H41,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Hot Holding Cabinets","Full Size",500,"Hot Holding Cabinets_Full Size",500,{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"Full Size\"),((40*N36)-(3.8*N36+203.5))*15*365/1000,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"Full Size\"),L36/15/365,\"\")","v":""},{"$f":"IF(AND('Equipment Input'!D42=\"Hot Holding Cabinets\",'Equipment Input'!E42=\"Full Size\"),'Equipment Input'!H42,\"\")","v":""},"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Fryers","Large Vat",300,"Fryers_Large Vat",300,2536,0.57999999999999996,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Griddles","All",300,{"$f":"G38&\"_\"&H38","v":"Griddles_All"},300,1907,0.44,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Convection Ovens","All",400,"Convection Ovens_All",400,1937,0.44,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Combination Ovens","All",1000,"Combination Ovens_All",1000,6368,1.45,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Ice Machines Batch","Ice Making Head",150,"Ice Machines Batch_Ice Making Head",150,1247,0.19,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Ice Machines Batch","Split System",100,"Ice Machines Batch_Split System",100,1181,0.18,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Ice Machines Batch","Self-Contained",50,"Ice Machines Batch_Self-Contained",{"$f":"I43","v":50},384,0.06,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Ice Machines Continuous","Ice Making Head",125,"Ice Machines Continuous_Ice Making Head",125,1862,0.28000000000000003,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Ice Machines Continuous","Split System",150,{"$f":"G45&\"_\"&H45","v":"Ice Machines Continuous_Split System"},150,2242,0.34,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Ice Machines Continuous","Self-Contained",75,"Ice Machines Continuous_Self-Contained",75,394,0.06,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Refrigerators","< 15 cubic feet",20,"Reach-in Refrigerators_< 15 cubic feet",20,453,5.1999999999999998E-2,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Refrigerators","15 - 30 cubic feet",30,"Reach-in Refrigerators_15 - 30 cubic feet",30,626,7.0999999999999994E-2,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Refrigerators","31 - 50 cubic feet",50,"Reach-in Refrigerators_31 - 50 cubic feet",50,982,0.112,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Refrigerators","> 50 cubic feet",100,"Reach-in Refrigerators_> 50 cubic feet",100,1456,0.16600000000000001,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Refrig","< 15 cubic feet",55,"Glass Door Reach-in Refrig_< 15 cubic feet",55,453,5.1999999999999998E-2,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Refrig","15 - 30 cubic feet",55,"Glass Door Reach-in Refrig_15 - 30 cubic feet",55,856,9.8000000000000004E-2,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Refrig","31 - 50 cubic feet",75,"Glass Door Reach-in Refrig_31 - 50 cubic feet",75,993,0.113,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Refrig","> 50 cubic feet",100,"Glass Door Reach-in Refrig_> 50 cubic feet",100,1358,0.155,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Freezers","< 15 cubic feet",50,"Reach-in Freezers_< 15 cubic feet",50,485,5.5E-2,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Freezers","15 - 30 cubic feet",75,"Reach-in Freezers_15 - 30 cubic feet",75,1307,0.14899999999999999,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Freezers","31 - 50 cubic feet",125,"Reach-in Freezers_31 - 50 cubic feet",125,2402,0.27400000000000002,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Reach-in Freezers","> 50 cubic feet",175,"Reach-in Freezers_> 50 cubic feet",175,3898,0.44500000000000001,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Freezers","< 15 cubic feet",75,"Glass Door Reach-in Freezers_< 15 cubic feet",75,485,5.5E-2,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Freezers","15 - 30 cubic feet",100,"Glass Door Reach-in Freezers_15 - 30 cubic feet",{"$f":"I60","v":100},3185,0.36299999999999999,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Freezers","31 - 50 cubic feet",150,"Glass Door Reach-in Freezers_31 - 50 cubic feet",150,5147,0.58699999999999997,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Glass Door Reach-in Freezers","> 50 cubic feet",200,"Glass Door Reach-in Freezers_> 50 cubic feet",200,7450,0.85,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Clothes Washers","Electric water heater",50,"Clothes Washers_Electric water heater",50,456,0,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Clothes Washers","Non-electric water heater",50,"Clothes Washers_Non-electric water heater",50,91,0,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Anti-Sweat Heater Controls","Cooler Doors",50,"Anti-Sweat Heater Controls_Cooler Doors",50,{"$f":"0.13*(90.7%-42.8%)*8766*1.25","v":682.32352500000002},{"$f":"0.13*(90.7%-42.8%)*1.25*0.36","v":2.8021500000000001E-2},null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Anti-Sweat Heater Controls","Freezer Doors",50,"Anti-Sweat Heater Controls_Freezer Doors",50,{"$f":"0.13*(90.7%-42.8%)*8276*1.5","v":773.01978000000008},{"$f":"0.13*(90.7%-42.8%)*1.5*0.3","v":2.8021500000000005E-2},null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Cooler replacing PSC",35,{"$f":"G67&\"_\"&H67","v":"ECM (Coolers/Freezers)_Walk-in Cooler replacing PSC"},50,1016,0.12,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Freezer replacing PSC",35,{"$f":"G68&\"_\"&H68","v":"ECM (Coolers/Freezers)_Walk-in Freezer replacing PSC"},50,1213,0.15,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Cooler replacing Shaded Poll",35,"ECM (Coolers/Freezers)_Walk-in Cooler replacing Shaded Poll",100,1016,0.12,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Walk-in Freezer replacing Shaded Poll",35,"ECM (Coolers/Freezers)_Walk-in Freezer replacing Shaded Poll",100,1213,0.15,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Reach-in Cooler",35,"ECM (Coolers/Freezers)_Reach-in Cooler",35,331,0.04,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Reach-in Freezer",35,"ECM (Coolers/Freezers)_Reach-in Freezer",35,395,0.05,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Display Cooler",35,"ECM (Coolers/Freezers)_Display Cooler",35,331,0.04,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"ECM (Coolers/Freezers)","Display Freezer",35,"ECM (Coolers/Freezers)_Display Freezer",35,395,0.05,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Refrigeration Night Covers","Freezers",5,"Refrigeration Night Covers_Freezers",5,252,0,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"Refrigeration Night Covers","Coolers",5,"Refrigeration Night Covers_Coolers",5,139,0,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) "]
[null,null,null,null,null,null,"LED Refrig Case Lighting","Coolers",25,"LED Refrig Case Lighting_Coolers",25,null,null,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) - Calc Embedded into Inputs"]
[null,null,null,null,null,null,"LED Refrig Case Lighting","Freezers",25,"LED Refrig Case Lighting_Freezers",25,null,null,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) - Calc Embedded into Inputs"]
[null,null,null,null,null,null,"LED Refrig Case Lighting Controls","Coolers",5,"LED Refrig Case Lighting Controls_Coolers",5,null,null,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) - Calc Embedded into Inputs"]
[null,null,null,null,null,null,"LED Refrig Case Lighting Controls","Freezers",5,"LED Refrig Case Lighting Controls_Freezers",5,null,null,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) - Calc Embedded into Inputs"]
[null,null,null,null,null,null,"Vending Machine Controls","Refrigerated",20,"Vending Machine Controls_Refrigerated",20,1613,0,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) - Calc Embedded into Inputs"]
[null,null,null,null,null,null,"Vending Machine Controls","Non-Refrigerated",10,"Vending Machine Controls_Non-Refrigerated",10,343,0,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) - Calc Embedded into Inputs"]
[null,null,null,null,null,null,"Personal Recept Occ Sensors","Power Strip with Occupancy Sensor",5,"Personal Recept Occ Sensors_Power Strip with Occupancy Sensor",5,43,0,null,"2023 South Carolina Commercial Energy Algorithm Manual (CEAM) - Calc Embedded into Inputs"]

{"sheet":"Version Tracking","index":12,"n_rows":32,"n_cols":5,"rows_kept":32,"cut":false,"hidden":true,"merged":[]}
[]
[]
[]
[null,"Current:",{"$f":"LOOKUP(2,1/(B1:B50001<>\"\"),B1:B50001)","v":14.3}]
[null,"Version","Notes","Date","Updated By"]
[null,"1.0","Initial creation of Food Service and High-Efficiency Equipment tool for SCANA.","2011-04-11","Drew Durkee"]
[null,"1.1","modify measure name length to fit vision number of character requirement","2011-04-15","O'Neil Morgan"]
[null,"1.2","modify measure name length to fit vision number of character requirement","2011-04-19","O'Neil Morgan"]
[null,"1.3","CREATE MEASURE CODE ","2011-05-05","O'Neil Morgan"]
[null,"1.4","update aeg tab","2011-05-26","O'Neil Morgan"]
[null,1.5,"updated EULs to align with BGE program","2011-07-05","Charlie Haack"]
[null,1.6,"Removed extra space from G45 and G46 of 'Lookups' tab","2011-07-19","Charlie Haack"]
[null,1.7,"add a space between LED Refrig and Case Lighting on the validation tab","2011-09-01","O'Neil Morgan"]
[null,1.8,"convert watts to kw for the LED Refrig and Case Lighting measure","2011-09-23","O'Neil Morgan"]
[null,1.9,"made adjustment to AEG tab so that savings are reported on a per unit basis","2011-10-20","O'Neil Morgan"]
[null,2,"Remove commas from validation tab info","2011-10-25","Colin Odell"]
[null,2.1,"made adjustment to kWsavings for ECM motor measure ","2012-01-17","O'Neil Morgan"]
[null,2.2000000000000002,"CEE Ice machine update","2012-02-25","CGO"]
[null,2.2999999999999998,"CEE Ice machine update","2012-05-30","O'Neil Morgan"]
[null,2.4,"Made adjustments for ECM in refrigeration cases and LED in reach in cases per ODC Instructions and SCEG Approval","2012-12-06","Drew Durkee"]
[null,2.5,"Adjusted the measure code for ice m/c to match the vision codes","2013-06-10","O'Neil Morgan"]
[null,3,"update saving to match SC Energy Algorithm Manual","2016-06-27","O'Neil Morgan"]
[null,3.2,"update aeg tab and input sheet"]
[null,3.3,"Adjusted the measure code for Refrig lighting ","2017-01-05","O'Neil Morgan"]
[null,3.4,"Add GDF IN VALIDATION TAB","2017-01-11","O'Neil Morgan"]
[null,3.5,"update increase incentives for 2017","2017-01-18","O'Neil Morgan"]
[null,3.6,"updated other incentives for 2017","2017-08-17","Rick Campana"]
[null,3.7,"Fixed errors related to hot holding cabinets and clothes washers","2017-10-11","Rick Campana"]
[null,3.8,"Updated savings calculations for case lighting & controls","2019-01-18","Rick Campana"]
[null,14.1,"QC'ed the measures with 2023 CEAM and have updated the numbers for Anti-Sweat Heater Controls and updated the Waste heat factor associated with LED Refrigerated Case Lighting for both cooler and freezer","2023-07-12","Thomaskutty Jaison"]
[null,14.2,"Added Glass Door Freezers to the Measure Type table on Validation Tab for AEG export","2024-02-23","Liv Stewart"]
[null,14.3,"Combined Application and Worksheet into 1 document","2024-03-28","Liv Stewart"]

{"sheet":"AEG Import","index":13,"n_rows":21,"n_cols":234,"rows_kept":21,"cut":false,"hidden":true,"merged":[]}
["Measure #","Import?","1st_Yr_Non_Resource_Benefits","Adjusted_Volume","AFUE","AHRI_Ref_number","Air_Leakage","amperage","Annual_Cords_Saved","Annual_Cords_Used","Annual_Gallons_Saved","Annual_Gallons_Used","Annual_Non_Resource_Benefits","Annual_Pounds_Saved","Annual_Pounds_Used","Annual_Therms_Saved","Annual_Therms_Used","Area_Lit","Avg_Wind_Speed","ballast_type_sel","Base_or_Efficiency_Case_sel","basecase_age","basecase_Capacity_or_size","basecase_efficiency","basecase_other","basecase_quantity","basecase_system_rating","basecase_type","basecase_unit_rating","Baseline_equipment_cost","Baseline_Installed_Cost","Baseline_system_age","BEF","Benefit_1_Description_sel","Benefit_1a_Description","Benefit_2_Description","Benefit_2a_Description","benefit_multiplier","Blower_Fan_E_Use","Blower_Fan_motor_control_sel","Boiler_Type_sel","BTU","BTU_Cool","BTU_Heat","Btuh","Building_Conditioned_Area","building_type_sel","Capacity","CEE_Tier_sel","CFM","CO2_Generator","CO2_Pt_Source_or_Meter","Comm_Coincidence","Comm_Coincidence_Factor","Commercial Spillover","Commercial_Free_Driver","Commercial_Free_Ridership","Commercial_Net_to_Gross_Ratio","Commercial_Snap_Back","Commissioned_sel","Control_Type_sel","Cooling_Bonus","COP","CRI","CTRL_Comm_Type_sel","Customer_refID","DeltaTemp","Description","discount_rate","Door_type_sel","Duct_Leakage","Economizer_Type_sel","EER","ef","Efficiency","Elec_Savings_Adj","Elec_Util_cust_Incentive","Eligibility_Status_sel","End_Use_sel","ENERGY_STAR_Compliant_sel","Equip_Orientation_sel","equipment_cost","Exist_Equip_Age","Exist_Equip_Life","Fed_Tax_Credit_Eligible_sel","Fixture_Efficiency","fixture_mounting_sel","Fixture_Size","fixture_style_sel","Flow","fuel_used_2_sel","fuel_used_3_sel","fuel_used_sel","Full_Cost_for_Retrofit","Full_Load_Hours","Full_Load_Hours_Cool","Full_Load_Hours_Heat","Gas_Util_Cust_Incentive","Geothermal_Loop_Type_sel","Green_Certification_sel","Heat_Exchanger_Type_sel","Heating_Penalty","Heating_Type_sel","HERS_rating","HiEff_Blower_Fan_sel","Horse_Power","Hrs_of_Use","HSPF","Hub_Height","Incentive_Per_Unit","Incremental_Installed_Cost","Install_Type_sel","Installed_Cost","Insulation_Location_sel","Insulation_Material_sel","IPLV","IRR","IsElectric","IsTested","kW_Impact","kw_pjm_peak_adjusted","kw_pjm_peak_unadjusted","kW_Summer_Gross","kW_Summer_Net","kw_ton_IPLV","kw_ton_peak","kW_Winter_Gross","kW_Winter_Net","kWh_Gross","kWh_Impact","kWh_Net","kwh_nonsummer_offpeak_adjusted","kwh_nonsummer_offpeak_unadjusted","kwh_nonsummer_peak_adjusted","kwh_nonsummer_peak_unadjusted","kwh_summer_offpeak_adjusted","kwh_summer_offpeak_unadjusted","kwh_summer_peak_adjusted","kwh_summer_peak_unadjusted","Lamp_Length","lamp_type_sel","Line_loss_kW","Line_loss_kWh","Load","LoadFactor","Loadshape_sel","Loan_Interest_Rate","Location","Lumens","Manufacturer","Manufacturer_Non_split_system","Manufacturer_Split_System_Coil","Manufacturer_Split_System_Condenser","Manufacturer_sub_components_1","Manufacturer_sub_components_2","Manufacturer_sub_components_3","MBtuh_Input","MBtuh_Output","Measure_Life","Meets_building_code_sel","MEF","Model","Motor_Enclosure_Type_sel","name","Name_Plate_Power_Rating","Natural_Gas_Savings_Adjustment","Natural_Gas_Savings_mmbtu","New_Baseline_Inst_Cost","nox","NPV","number_lamps","Number_of_Panes","Number_Units","Output_Watts","Phase_sel","Pool_pump_type_sel","pool_size","pool_type_sel","Program_Name","quantity","R_value","rebate_kwh","rebate_ton","rebate_watt","refid","Resi_coincidence","Resi_Coincidence_factor","Residential Spillover","Residential_Freedriver","Residential_Freeridership","Residential_Net_to_Gross_Ratio","Residential_Snap_back","RLA","RLA_Actual","RNC_Tier_sel","RPM","SEER","SENS_Latent_Total","Sensor_Type_sel","Serial_number","SHGC","Solar_AC_kW_Net","sox","SRI","Steady_state_efficiency","Style","Thermal_efficiency","Thickness","Tilt_Angle","Tons","Tons_Controlled","Tune_up_equipment_type_sel","turbine_rating_capacity","U_value","Units_Controlled_by_Control","Unused_Incentive","userid","ventilation_type_sel","Volts","Volume_ft3","Warranty","Water","Water_Consumption","Water_Factor","water_gallons_per_minute_ton","Water_Heating_Type_sel","Water_Storage_Capacity","Wattage","Watts_sqft","Watts_sqft_Saved","Wind_Output_Reduction","Window_Frame_Material_sel","Window_Gas_sel","Window_Type_sel"]
[{"$f":"VLOOKUP(FH2,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L23=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C23","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N23/IF(FX2=0,1, FX2)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(BY2=\"\",FX2=\"\"),\"\",BY2)","v":{"$error":"#VALUE!"}},null,{"$f":"'Equipment Input'!E23","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R23,'Equipment Input'!S23,'Equipment Input'!T23)/IF(FX2=0,1,FX2)","v":0},null,null,{"$f":"DP2","v":0},null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O23,'Equipment Input'!P23,'Equipment Input'!Q23)/IF(FX2=0,1,FX2)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F23","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH2,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH2,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H23","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D23, \" \", 'Equipment Input'!E23)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L23","v":0}]
[{"$f":"VLOOKUP(FH3,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L24=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C24","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N24/IF(FX3=0,1, FX3)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(OR(BY3=\"\",FX3=\"\"),\"\",BY3)","v":{"$error":"#VALUE!"}},null,{"$f":"'Equipment Input'!E24","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R24,'Equipment Input'!S24,'Equipment Input'!T24)/IF(FX3=0,1,FX3)","v":0},null,null,{"$f":"DP3","v":0},null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O24,'Equipment Input'!P24,'Equipment Input'!Q24)/IF(FX3=0,1,FX3)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F24","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH3,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH3,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H24","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D24, \" \", 'Equipment Input'!E24)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L24","v":0}]
[{"$f":"VLOOKUP(FH4,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L25=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C25","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N25/IF(FX4=0,1, FX4)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E25","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R25,'Equipment Input'!S25,'Equipment Input'!T25)/IF(FX4=0,1,FX4)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O25,'Equipment Input'!P25,'Equipment Input'!Q25)/IF(FX4=0,1,FX4)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F25","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH4,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH4,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H25","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D25, \" \", 'Equipment Input'!E25)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L25","v":0}]
[{"$f":"VLOOKUP(FH5,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L26=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C26","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N26/IF(FX5=0,1, FX5)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E26","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R26,'Equipment Input'!S26,'Equipment Input'!T26)/IF(FX5=0,1,FX5)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O26,'Equipment Input'!P26,'Equipment Input'!Q26)/IF(FX5=0,1,FX5)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F26","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH5,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH5,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H26","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D26, \" \", 'Equipment Input'!E26)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L26","v":0}]
[{"$f":"VLOOKUP(FH6,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L27=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C27","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N27/IF(FX6=0,1, FX6)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E27","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R27,'Equipment Input'!S27,'Equipment Input'!T27)/IF(FX6=0,1,FX6)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O27,'Equipment Input'!P27,'Equipment Input'!Q27)/IF(FX6=0,1,FX6)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F27","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH6,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH6,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H27","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D27, \" \", 'Equipment Input'!E27)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L27","v":0}]
[{"$f":"VLOOKUP(FH7,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L28=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C28","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N28/IF(FX7=0,1, FX7)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E28","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R28,'Equipment Input'!S28,'Equipment Input'!T28)/IF(FX7=0,1,FX7)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O28,'Equipment Input'!P28,'Equipment Input'!Q28)/IF(FX7=0,1,FX7)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F28","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH7,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH7,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H28","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D28, \" \", 'Equipment Input'!E28)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L28","v":0}]
[{"$f":"VLOOKUP(FH8,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L29=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C29","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N29/IF(FX8=0,1, FX8)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E29","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R29,'Equipment Input'!S29,'Equipment Input'!T29)/IF(FX8=0,1,FX8)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O29,'Equipment Input'!P29,'Equipment Input'!Q29)/IF(FX8=0,1,FX8)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F29","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH8,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH8,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H29","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D29, \" \", 'Equipment Input'!E29)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L29","v":0}]
[{"$f":"VLOOKUP(FH9,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L30=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C30","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N30/IF(FX9=0,1, FX9)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E30","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R30,'Equipment Input'!S30,'Equipment Input'!T30)/IF(FX9=0,1,FX9)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O30,'Equipment Input'!P30,'Equipment Input'!Q30)/IF(FX9=0,1,FX9)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F30","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH9,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH9,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H30","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D30, \" \", 'Equipment Input'!E30)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L30","v":0}]
[{"$f":"VLOOKUP(FH10,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L31=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C31","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N31/IF(FX10=0,1, FX10)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E31","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R31,'Equipment Input'!S31,'Equipment Input'!T31)/IF(FX10=0,1,FX10)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O31,'Equipment Input'!P31,'Equipment Input'!Q31)/IF(FX10=0,1,FX10)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F31","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH10,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH10,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H31","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D31, \" \", 'Equipment Input'!E31)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L31","v":0}]
[{"$f":"VLOOKUP(FH11,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L32=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C32","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N32/IF(FX11=0,1, FX11)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E32","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R32,'Equipment Input'!S32,'Equipment Input'!T32)/IF(FX11=0,1,FX11)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O32,'Equipment Input'!P32,'Equipment Input'!Q32)/IF(FX11=0,1,FX11)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F32","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH11,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH11,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H32","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D32, \" \", 'Equipment Input'!E32)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L32","v":0}]
[{"$f":"VLOOKUP(FH12,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L33=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C33","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N33/IF(FX12=0,1, FX12)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E33","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R33,'Equipment Input'!S33,'Equipment Input'!T33)/IF(FX12=0,1,FX12)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O33,'Equipment Input'!P33,'Equipment Input'!Q33)/IF(FX12=0,1,FX12)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F33","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH12,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH12,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H33","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D33, \" \", 'Equipment Input'!E33)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L33","v":0}]
[{"$f":"VLOOKUP(FH13,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L34=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C34","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N34/IF(FX13=0,1, FX13)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E34","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R34,'Equipment Input'!S34,'Equipment Input'!T34)/IF(FX13=0,1,FX13)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O34,'Equipment Input'!P34,'Equipment Input'!Q34)/IF(FX13=0,1,FX13)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F34","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH13,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH13,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H34","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D34, \" \", 'Equipment Input'!E34)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L34","v":0}]
[{"$f":"VLOOKUP(FH14,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L35=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C35","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N35/IF(FX14=0,1, FX14)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E35","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R35,'Equipment Input'!S35,'Equipment Input'!T35)/IF(FX14=0,1,FX14)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O35,'Equipment Input'!P35,'Equipment Input'!Q35)/IF(FX14=0,1,FX14)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F35","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH14,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH14,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H35","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D35, \" \", 'Equipment Input'!E35)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L35","v":0}]
[{"$f":"VLOOKUP(FH15,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L36=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C36","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N36/IF(FX15=0,1, FX15)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E36","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R36,'Equipment Input'!S36,'Equipment Input'!T36)/IF(FX15=0,1,FX15)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O36,'Equipment Input'!P36,'Equipment Input'!Q36)/IF(FX15=0,1,FX15)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F36","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH15,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH15,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H36","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D36, \" \", 'Equipment Input'!E36)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L36","v":0}]
[{"$f":"VLOOKUP(FH16,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L37=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C37","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N37/IF(FX16=0,1, FX16)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E37","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R37,'Equipment Input'!S37,'Equipment Input'!T37)/IF(FX16=0,1,FX16)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O37,'Equipment Input'!P37,'Equipment Input'!Q37)/IF(FX16=0,1,FX16)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F37","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH16,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH16,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H37","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D37, \" \", 'Equipment Input'!E37)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L37","v":0}]
[{"$f":"VLOOKUP(FH17,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L38=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C38","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N38/IF(FX17=0,1, FX17)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E38","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R38,'Equipment Input'!S38,'Equipment Input'!T38)/IF(FX17=0,1,FX17)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O38,'Equipment Input'!P38,'Equipment Input'!Q38)/IF(FX17=0,1,FX17)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F38","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH17,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH17,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H38","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D38, \" \", 'Equipment Input'!E38)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L38","v":0}]
[{"$f":"VLOOKUP(FH18,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L39=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C39","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N39/IF(FX18=0,1, FX18)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E39","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R39,'Equipment Input'!S39,'Equipment Input'!T39)/IF(FX18=0,1,FX18)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O39,'Equipment Input'!P39,'Equipment Input'!Q39)/IF(FX18=0,1,FX18)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F39","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH18,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH18,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H39","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D39, \" \", 'Equipment Input'!E39)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L39","v":0}]
[{"$f":"VLOOKUP(FH19,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L40=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C40","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N40/IF(FX19=0,1, FX19)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E40","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R40,'Equipment Input'!S40,'Equipment Input'!T40)/IF(FX19=0,1,FX19)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O40,'Equipment Input'!P40,'Equipment Input'!Q40)/IF(FX19=0,1,FX19)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F40","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH19,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH19,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H40","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D40, \" \", 'Equipment Input'!E40)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L40","v":0}]
[{"$f":"VLOOKUP(FH20,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L41=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C41","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N41/IF(FX20=0,1, FX20)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E41","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R41,'Equipment Input'!S41,'Equipment Input'!T41)/IF(FX20=0,1,FX20)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O41,'Equipment Input'!P41,'Equipment Input'!Q41)/IF(FX20=0,1,FX20)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F41","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH20,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH20,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H41","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D41, \" \", 'Equipment Input'!E41)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L41","v":0}]
[{"$f":"VLOOKUP(FH21,Validation!AE:AF,2,FALSE)","v":{"$error":"#N/A"}},{"$f":"IF('Equipment Input'!L42=\"\",\"No\",\"Yes\")","v":"No"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!C42","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!N42/IF(FX21=0,1, FX21)","v":{"$error":"#VALUE!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$error":"#VALUE!"},null,{"$f":"'Equipment Input'!E42","v":0},null,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!R42,'Equipment Input'!S42,'Equipment Input'!T42)/IF(FX21=0,1,FX21)","v":0},null,null,0,null,null,null,null,null,null,{"$f":"SUM('Equipment Input'!O42,'Equipment Input'!P42,'Equipment Input'!Q42)/IF(FX21=0,1,FX21)","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!F42","v":0},null,null,null,null,null,null,null,null,{"$f":"IF(ISERROR(VLOOKUP(FH21,Validation!$AE$3:$AG$56,3,FALSE)),0,VLOOKUP(FH21,Validation!$AE$3:$AG$56,3,FALSE))","v":0},null,null,{"$f":"'Equipment Input'!H42","v":0},null,{"$f":"CONCATENATE('Equipment Input'!D42, \" \", 'Equipment Input'!E42)","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"'Equipment Input'!L42","v":0}]